{"id":584202,"date":"2026-02-22T10:02:13","date_gmt":"2026-02-22T14:02:13","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=584202"},"modified":"2026-02-26T07:22:48","modified_gmt":"2026-02-26T11:22:48","slug":"senar-mt-promove-integracao-e-inicia-ano-letivo","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2026\/02\/22\/senar-mt-promove-integracao-e-inicia-ano-letivo\/","title":{"rendered":"Senar MT promove integra\u00e7\u00e3o e inicia ano letivo na Escola Agr\u00edcola Senar MT"},"content":{"rendered":"\n<p>O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar MT) realizou, na sexta-feira (20), o encontro de integra\u00e7\u00e3o entre alunos, familiares e comunidade escolar da Escola Agr\u00edcola Senar, unidade Ranch\u00e3o, em Nova Mutum, marcando o in\u00edcio do ano letivo e o acolhimento dos novos estudantes do Curso T\u00e9cnico em Agropecu\u00e1ria. O evento reuniu aproximadamente 300 pessoas, entre pais, alunos, equipe pedag\u00f3gica e representantes das institui\u00e7\u00f5es parceiras.<\/p>\n\n\n\n<p>Neste ano, a escola inicia as atividades com 102 estudantes, sendo 41 ingressantes e 61 que v\u00e3o dar continuidade \u00e0 forma\u00e7\u00e3o t\u00e9cnica. A programa\u00e7\u00e3o teve como objetivo apresentar a organiza\u00e7\u00e3o da institui\u00e7\u00e3o, o calend\u00e1rio letivo, a matriz curricular e as diretrizes pedag\u00f3gicas, al\u00e9m de promover o alinhamento de informa\u00e7\u00f5es com as fam\u00edlias e fortalecer a parceria no processo educacional.<\/p>\n\n\n\n<p>De acordo com o gerente de Educa\u00e7\u00e3o Formal do Senar MT, Pedro Souza, o encontro \u00e9 um momento estrat\u00e9gico para aproximar alunos, familiares e equipe escolar. \u201cConclu\u00edmos mais um dia de integra\u00e7\u00e3o fam\u00edlia e escola, reunindo alunos novatos, veteranos e seus familiares. \u00c9 um evento que marca o in\u00edcio do ano letivo e refor\u00e7a o compromisso do Senar e do Sistema Famato com a forma\u00e7\u00e3o de qualidade. Aos novos alunos, deixo uma mensagem de incentivo: dediquem-se, aproveitem as oportunidades e contem conosco nessa jornada\u201d, afirmou.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.50-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-584204\" style=\"width:690px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.50-1-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.50-1-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.50-1-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.50-1-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.50-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Dia de integra\u00e7\u00e3o entre alunos, familiares e comunidade na Escola Agr\u00edcola Senar MT<\/figcaption><\/figure><\/div>\n\n\n<p>O diretor da Escola Agr\u00edcola Senar MT, Jos\u00e9 Paulo, destacou que a integra\u00e7\u00e3o \u00e9 fundamental para construir um ambiente de confian\u00e7a e acolhimento. \u201cEsse \u00e9 o primeiro evento do ano letivo e tem como principal finalidade apresentar a institui\u00e7\u00e3o, suas normas e diretrizes, al\u00e9m de acolher os novos alunos e suas fam\u00edlias. Nosso compromisso \u00e9 oferecer uma educa\u00e7\u00e3o de qualidade, preparando esses jovens para o mercado de trabalho e para os desafios do setor agropecu\u00e1rio\u201d, disse.<\/p>\n\n\n\n<p>Para os pais, o momento representa seguran\u00e7a e confian\u00e7a na forma\u00e7\u00e3o dos filhos. A m\u00e3e do estudante Eduardo Roberto Coelho, Estef\u00e2nia Roberto, destacou o orgulho pela conquista do filho. \u201cEstou muito feliz e orgulhosa por ele estar correndo atr\u00e1s do sonho dele. A expectativa \u00e9 a melhor poss\u00edvel, porque sabemos que o setor agropecu\u00e1rio oferece muitas oportunidades\u201d, relatou.<\/p>\n\n\n\n<p>Aluno do \u00faltimo ano, Jo\u00e3o Victor Mascarenhas compartilhou sua trajet\u00f3ria e incentivou os novos estudantes. Natural de S\u00e3o F\u00e9lix do Xingu (PA), ele afirmou que encontrou na escola a oportunidade de se preparar para o futuro. \u201cSempre tive o sonho de estudar em Mato Grosso e me qualificar para trabalhar no agro. Estar aqui \u00e9 emocionante. Aos novos alunos, digo que vale a pena persistir e aproveitar cada oportunidade\u201d, afirmou.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584206\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-3-1024x683.jpeg\" alt=\"\" class=\"wp-image-584206\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-3-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-3-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-3-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-3-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-3.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584207\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-584207\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-2-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-2-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-2-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-2-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-2.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584208\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1024x683.jpeg\" alt=\"\" class=\"wp-image-584208\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584209\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-3-1024x683.jpeg\" alt=\"\" class=\"wp-image-584209\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-3-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-3-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-3-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-3-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-3.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584210\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-584210\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-1-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-1-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-1-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-1-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"584211\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.52-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-584211\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.52-2-768x1024.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.52-2-225x300.jpeg 225w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.52-2-640x853.jpeg 640w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.52-2-150x200.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.52-2.jpeg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584215\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-584215\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.51-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"584216\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-584216\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-2-1024x683.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-2-300x200.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-2-768x512.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-2-150x100.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-2.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Evento reuniu cerca de 300 pessoas, recebeu novos estudantes e fortaleceu a parceria entre escola e fam\u00edlia <\/p>\n","protected":false},"author":76,"featured_media":584205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-584202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"Rosangela Milles","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/rosangela-miles\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2026\/02\/WhatsApp-Image-2026-02-20-at-18.48.49-300x225.jpeg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 3 meses atr\u00e1s","modified":"Atualizado 3 meses atr\u00e1s"},"absolute_dates":{"created":"Publicado em 22 de fevereiro de 2026","modified":"Atualizado em 26 de fevereiro de 2026"},"absolute_dates_time":{"created":"Publicado em 22 de fevereiro de 2026 10:02","modified":"Atualizado em 26 de fevereiro de 2026 07:22"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/584202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=584202"}],"version-history":[{"count":6,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/584202\/revisions"}],"predecessor-version":[{"id":584325,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/584202\/revisions\/584325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/584205"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=584202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=584202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=584202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}