{"id":563164,"date":"2025-01-07T13:46:51","date_gmt":"2025-01-07T17:46:51","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=563164"},"modified":"2025-01-07T14:02:26","modified_gmt":"2025-01-07T18:02:26","slug":"ultimos-dias-para-a-pre-matricula-na-escola-agricola-ranchao","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2025\/01\/07\/ultimos-dias-para-a-pre-matricula-na-escola-agricola-ranchao\/","title":{"rendered":"\u00daltimos dias para a pr\u00e9-matr\u00edcula na Escola Agr\u00edcola Ranch\u00e3o"},"content":{"rendered":"\n<p>O prazo para a realiza\u00e7\u00e3o da pr\u00e9-matr\u00edcula na Escola Agr\u00edcola Ranch\u00e3o est\u00e1 chegando ao fim. Os interessados em garantir uma vaga no Curso T\u00e9cnico de n\u00edvel m\u00e9dio em Agropecu\u00e1ria t\u00eam at\u00e9 o dia 10 de janeiro para realizar o processo.<\/p>\n\n\n\n<p>Localizada em Nova Mutum, a escola \u00e9 reconhecida por sua excel\u00eancia no ensino t\u00e9cnico agr\u00edcola e na forma\u00e7\u00e3o de jovens para atuar no campo. Oferecendo uma estrutura moderna e ensino de qualidade, a institui\u00e7\u00e3o prepara os alunos com aprendizado pr\u00e1tico e te\u00f3rico nas principais \u00e1reas do agroneg\u00f3cio, alinhando-se \u00e0s demandas do mercado e \u00e0s inova\u00e7\u00f5es tecnol\u00f3gicas do setor.<\/p>\n\n\n\n<p>S\u00e3o oferecidas 160 vagas para os candidatos que est\u00e3o cursando a partir do 2\u00ba ano do Ensino M\u00e9dio e para aqueles que j\u00e1 conclu\u00edram.<\/p>\n\n\n\n<p>A lista preliminar dos aprovados ser\u00e1 publicada no portal eletr\u00f4nico do processo seletivo no dia 17 de janeiro de 2025. As aulas devem iniciar a partir do dia 3 de fevereiro.<\/p>\n\n\n\n<p>Para realizar a pr\u00e9-matr\u00edcula \u00e9 s\u00f3 <strong><a href=\"https:\/\/educacaoformal.senarmt.org.br:8095\/FrameHTML\/web\/app\/edu\/portalprocessoseletivo\/#\/es\/informacoes\">CLICAR AQUI.<br><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prazo para a realiza\u00e7\u00e3o da pr\u00e9-matr\u00edcula na Escola Agr\u00edcola Ranch\u00e3o est\u00e1 chegando ao fim. Os interessados em garantir uma vaga no Curso T\u00e9cnico de n\u00edvel m\u00e9dio em Agropecu\u00e1ria t\u00eam at\u00e9 o dia 10 de janeiro para realizar o processo. Localizada em Nova Mutum, a escola \u00e9 reconhecida por sua excel\u00eancia no ensino t\u00e9cnico agr\u00edcola [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":563165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[863],"tags":[],"class_list":["post-563164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacao-profissional"],"acf":[],"author_meta":{"display_name":"Ana Frutuoso","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/ana-frutuoso\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2025\/01\/WhatsApp-Image-2025-01-07-at-10.51-300x161.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/formacao-profissional\/\" class=\"advgb-post-tax-term\">FORMA\u00c7\u00c3O PROFISSIONAL<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FORMA\u00c7\u00c3O PROFISSIONAL<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 1 ano atr\u00e1s","modified":"Atualizado 1 ano atr\u00e1s"},"absolute_dates":{"created":"Publicado em 7 de janeiro de 2025","modified":"Atualizado em 7 de janeiro de 2025"},"absolute_dates_time":{"created":"Publicado em 7 de janeiro de 2025 13:46","modified":"Atualizado em 7 de janeiro de 2025 14:02"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=563164"}],"version-history":[{"count":2,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563164\/revisions"}],"predecessor-version":[{"id":563167,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563164\/revisions\/563167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/563165"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=563164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=563164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=563164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}