{"id":563084,"date":"2024-12-14T15:44:02","date_gmt":"2024-12-14T19:44:02","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=563084"},"modified":"2024-12-14T15:44:05","modified_gmt":"2024-12-14T19:44:05","slug":"alunos-da-escola-agricola-ranchao-celebram-formatura-em-noite-de-homenagens-e-emocao","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2024\/12\/14\/alunos-da-escola-agricola-ranchao-celebram-formatura-em-noite-de-homenagens-e-emocao\/","title":{"rendered":"Alunos da Escola Agr\u00edcola Ranch\u00e3o celebram formatura em noite de homenagens e emo\u00e7\u00e3o"},"content":{"rendered":"\n<p>Na noite desta sexta-feira (13), o Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso promoveu a cerim\u00f4nia de formatura dos alunos da Escola Agr\u00edcola Ranch\u00e3o, em Nova Mutum. Amigos, familiares e autoridades prestigiaram o evento, que marcou o encerramento de uma jornada repleta de aprendizado e dedica\u00e7\u00e3o.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<p>Durante o evento, os formandos foram homenageados por suas trajet\u00f3rias, que inclu\u00edram aulas te\u00f3ricas, atividades pr\u00e1ticas no campo e viv\u00eancias que os prepararam para os desafios da vida no agroneg\u00f3cio.<\/p>\n<\/div>\n\n\n\n<p>\u201cPara mim, \u00e9 uma enorme satisfa\u00e7\u00e3o estar aqui hoje me formando, pois considero isso um grande avan\u00e7o, algo que transformou minha vida\u201d, disse Hendel Cau\u00e3 Lima, um dos alunos formados.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.01.37-768x1024.jpeg\" alt=\"\" class=\"wp-image-563086\" style=\"width:309px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.01.37-768x1024.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.01.37-225x300.jpeg 225w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.01.37-640x853.jpeg 640w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.01.37-150x200.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.01.37.jpeg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n<p>De acordo com o presidente do Sindicato Rural de Nova Mutum, a Escola Agr\u00edcola Ranch\u00e3o transforma vidas por meio da educa\u00e7\u00e3o no campo, abrindo portas para que os jovens desenvolvam suas habilidades e contribuam para o crescimento do setor agropecu\u00e1rio no estado.<\/p>\n\n\n\n<p>\u201c\u00c9 muito importante para o nosso munic\u00edpio e para o nosso estado, pois contaremos com pessoas capacitadas para trabalhar no campo, contribuindo para uma produ\u00e7\u00e3o cada vez mais eficiente e sustent\u00e1vel. Para o nosso sindicato, \u00e9 uma honra participar desse momento\u201d, explicou Paulo Zen.<\/p>\n\n\n\n<p>A festa de formatura refor\u00e7a o compromisso do Senar-MT em formar profissionais para atuar no campo. A Escola Agr\u00edcola Ranch\u00e3o oferece um curr\u00edculo que vai al\u00e9m de um certificado de conclus\u00e3o, preparando os alunos com experi\u00eancias pr\u00e1ticas essenciais para a atua\u00e7\u00e3o como t\u00e9cnicos em Agropecu\u00e1ria.<\/p>\n\n\n\n<p>\u201cTenho certeza de que a institui\u00e7\u00e3o est\u00e1 elevando o n\u00edvel da qualidade do ensino, especialmente na forma\u00e7\u00e3o t\u00e9cnica, que \u00e9 t\u00e3o necess\u00e1ria atualmente\u201d, comentou o prefeito de Nova Mutum, Leandro F\u00e9lix.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta sexta-feira (13), o Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso promoveu a cerim\u00f4nia de formatura dos alunos da Escola Agr\u00edcola Ranch\u00e3o, em Nova Mutum. Amigos, familiares e autoridades prestigiaram o evento, que marcou o encerramento de uma jornada repleta de aprendizado e dedica\u00e7\u00e3o. Durante o evento, os formandos foram homenageados por [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":563085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-563084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"Ana Frutuoso","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/ana-frutuoso\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/WhatsApp-Image-2024-12-14-at-15.02.13-300x225.jpeg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 1 ano atr\u00e1s","modified":"Atualizado 1 ano atr\u00e1s"},"absolute_dates":{"created":"Publicado em 14 de dezembro de 2024","modified":"Atualizado em 14 de dezembro de 2024"},"absolute_dates_time":{"created":"Publicado em 14 de dezembro de 2024 15:44","modified":"Atualizado em 14 de dezembro de 2024 15:44"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=563084"}],"version-history":[{"count":6,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563084\/revisions"}],"predecessor-version":[{"id":563092,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563084\/revisions\/563092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/563085"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=563084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=563084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=563084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}