{"id":563011,"date":"2024-12-10T08:25:49","date_gmt":"2024-12-10T12:25:49","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=563011"},"modified":"2024-12-10T20:33:17","modified_gmt":"2024-12-11T00:33:17","slug":"com-apoio-do-senar-mt-familia-aumenta-producao-de-leite-e-melhora-gestao-da-propriedade","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2024\/12\/10\/com-apoio-do-senar-mt-familia-aumenta-producao-de-leite-e-melhora-gestao-da-propriedade\/","title":{"rendered":"Com apoio do Senar-MT, fam\u00edlia aumenta produ\u00e7\u00e3o de leite e melhora gest\u00e3o da propriedade"},"content":{"rendered":"\n<p>No S\u00edtio Uni\u00e3o, localizado em Porto dos Ga\u00fachos, Regina Oliveira Batista encontrou, h\u00e1 mais de 30 anos, a oportunidade de transformar sua paix\u00e3o pela bovinocultura de leite em um sustento para a fam\u00edlia. Inicialmente, a produ\u00e7\u00e3o era simples, focada na confec\u00e7\u00e3o de queijo e iogurte para complementar a alimenta\u00e7\u00e3o dos filhos. Ao longo do tempo, a realidade mudou significativamente ap\u00f3s a chegada e apoio do Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT).<\/p>\n\n\n\n<p>&nbsp;\u201cAos 20 anos de idade, comecei com cerca de 20 litros de leite. As vacas que produziam de 3 a 4 litros de leite para mim j\u00e1 eram preciosas e estavam produzindo com excel\u00eancia, j\u00e1 uma vaca de 5 litros era o m\u00e1ximo. Assim, comecei a ver que dava para sustentar e alimentar as crian\u00e7as com o leite, e tudo foi melhorando. Uma vaca de leite para mim \u00e9 valiosa\u201d, conta Regina.<\/p>\n\n\n\n<p>A mudan\u00e7a na propriedade come\u00e7ou em 2021, quando a Assist\u00eancia T\u00e9cnica e Gerencial em Bovinocultura de Leite trouxe planejamento para auxiliar a produtora na gest\u00e3o do s\u00edtio e no aumento da produ\u00e7\u00e3o. A\u00e7\u00f5es e modelo de manejo foram implementados pela t\u00e9cnica credenciada do Senar-MT, Vanusa Lara.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170226-1024x576.jpg\" alt=\"\" class=\"wp-image-563041\" style=\"width:538px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170226-1024x576.jpg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170226-300x169.jpg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170226-768x432.jpg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170226-150x84.jpg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170226.jpg 1458w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>\u201cDesde a primeira visita, fizemos um diagn\u00f3stico de produtividade que mostrou que um dos desafios encontrados era o elevado custo de produ\u00e7\u00e3o, al\u00e9m da falta de gest\u00e3o em anota\u00e7\u00f5es de dados, que quase n\u00e3o existiam ou eram antigas e desatualizadas. Ap\u00f3s alinhar a gest\u00e3o, partimos para a parte t\u00e9cnica, lidando com a mortalidade dos bezerros e conseguindo reduzir tamb\u00e9m o custo de produ\u00e7\u00e3o, que caiu 40% em 2023 em rela\u00e7\u00e3o ao ano anterior\u201d, explica Lara.<\/p>\n\n\n\n<p>Estrat\u00e9gias que refletiram tamb\u00e9m no fortalecimento da produ\u00e7\u00e3o leite na propriedade. Antes da chegada do Senar-MT, as vacas produziam oito litros e atualmente est\u00e3o produzindo dez litros, o que representa um aumento anual de 27%. Segundo a t\u00e9cnica de campo, os n\u00fameros s\u00e3o resultados de um planejamento mais eficaz durante o ano.<\/p>\n\n\n\n<p>\u201cO Senar sempre esteve acompanhando e orientando, mostrando o caminho mais f\u00e1cil, e isso \u00e9 importante porque ajuda pessoas que realmente desejam sobreviver daquilo que fazem\u201d, diz Regina.<\/p>\n\n\n\n<p>O amor e a dedica\u00e7\u00e3o pelo trabalho no campo atravessam gera\u00e7\u00f5es e inspirou M\u00f4nica Bruna de Oliveira, filha da Regina. Atualmente, ela cuida do gerenciamento do s\u00edtio. Com o aux\u00edlio e instru\u00e7\u00e3o da t\u00e9cnica do Senar-MT, foi poss\u00edvel organizar as planilhas, al\u00e9m de melhorar a gest\u00e3o dos custos de produ\u00e7\u00e3o e a comercializa\u00e7\u00e3o do leite.<\/p>\n\n\n\n<p>Para o ano de 2025, a fam\u00edlia da Regina possui planos que s\u00e3o poss\u00edveis gra\u00e7as \u00e0 ajuda do Senar-MT. O objetivo \u00e9 implantar a produ\u00e7\u00e3o de milho para a fabrica\u00e7\u00e3o de silagem e dessa forma complementar a alimenta\u00e7\u00e3o que j\u00e1 \u00e9 feita com capia\u00e7u e cana-de-a\u00e7\u00facar.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170345-1024x576.jpg\" alt=\"\" class=\"wp-image-563042\" style=\"width:608px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170345-1024x576.jpg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170345-300x169.jpg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170345-768x432.jpg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170345-150x84.jpg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/Captura-de-tela-2024-12-06-170345.jpg 1461w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>M\u00f4nica relata que, ao longo do tempo, criou um amor pelos animais e, segundo ela, o que traz alegria \u00e9 ver a vida sendo cuidada. Com um filho, seu planejamento para o futuro \u00e9 continuar o trabalho para que o S\u00edtio Uni\u00e3o prospere ainda mais.<\/p>\n\n\n\n<p>\u201cPretendo passar todo o conhecimento adquirido com meus pais para o meu filho, para criar um legado e crescer juntos, sempre pensando em como melhorar a propriedade para que se torne cada vez melhor e mais produtiva\u201d.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No S\u00edtio Uni\u00e3o, localizado em Porto dos Ga\u00fachos, Regina Oliveira Batista encontrou, h\u00e1 mais de 30 anos, a oportunidade de transformar sua paix\u00e3o pela bovinocultura de leite em um sustento para a fam\u00edlia. Inicialmente, a produ\u00e7\u00e3o era simples, focada na confec\u00e7\u00e3o de queijo e iogurte para complementar a alimenta\u00e7\u00e3o dos filhos. Ao longo do tempo, [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":563040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-563011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assistencia-tecnica-e-gerencial-ateg"],"acf":[],"author_meta":{"display_name":"Ana Frutuoso","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/ana-frutuoso\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/12\/IMG_3889-300x169.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/assistencia-tecnica-e-gerencial-ateg\/\" class=\"advgb-post-tax-term\">Assist\u00eancia T\u00e9cnica e Gerencial (ATeG)<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Assist\u00eancia T\u00e9cnica e Gerencial (ATeG)<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 1 ano atr\u00e1s","modified":"Atualizado 1 ano atr\u00e1s"},"absolute_dates":{"created":"Publicado em 10 de dezembro de 2024","modified":"Atualizado em 10 de dezembro de 2024"},"absolute_dates_time":{"created":"Publicado em 10 de dezembro de 2024 08:25","modified":"Atualizado em 10 de dezembro de 2024 20:33"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=563011"}],"version-history":[{"count":4,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563011\/revisions"}],"predecessor-version":[{"id":563049,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/563011\/revisions\/563049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/563040"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=563011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=563011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=563011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}