{"id":562514,"date":"2024-11-15T10:36:53","date_gmt":"2024-11-15T14:36:53","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=562514"},"modified":"2024-11-15T10:51:57","modified_gmt":"2024-11-15T14:51:57","slug":"sistema-famato-senar-recebe-2o-premio-dimas-em-noite-de-homenagens","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2024\/11\/15\/sistema-famato-senar-recebe-2o-premio-dimas-em-noite-de-homenagens\/","title":{"rendered":"Sistema Famato\/Senar recebe &#8220;2\u00ba Pr\u00eamio Dimas&#8221; em noite de homenagens"},"content":{"rendered":"\n<p>Na noite desta quarta-feira (14), o Sistema Famato\/Senar foi homenageado pelo Minist\u00e9rio P\u00fablico de Mato Grosso com o &#8220;2\u00ba Pr\u00eamio Dimas&#8221;, no audit\u00f3rio da sede das Promotorias de Justi\u00e7a de Cuiab\u00e1. O Senar-MT \u00e9 uma das institui\u00e7\u00f5es que contribu\u00edram para a realiza\u00e7\u00e3o do projeto Reconstruindo Sonhos em unidades prisionais de Mato Grosso, no decorrer de 2024.<\/p>\n\n\n\n<p>O superintendente do Senar-MT, Marcelo Lupatini, e o consultor jur\u00eddico da Famato, Rodrigo Bressane, participaram da solenidade fortalecendo o apoio \u00e0 ressocializa\u00e7\u00e3o, por meio da qualifica\u00e7\u00e3o e habilita\u00e7\u00e3o para o mercado de trabalho de reeducandos. <\/p>\n\n\n\n<p>O projeto \u00e9 executado em duas etapas. Na primeira, chamada de \u201cAmplia\u00e7\u00e3o do sentido da vida\u201d, s\u00e3o realizados 12 encontros semanais presenciais dentro das unidades, nos quais s\u00e3o abordados com os participantes temas como valores, humaniza\u00e7\u00e3o e espiritualidade, rela\u00e7\u00f5es interpessoais, fam\u00edlia, comunica\u00e7\u00e3o, trabalho, perspectiva de futuro, planejamento, entre outros. Terminada essa fase, o projeto segue com a oferta de cursos profissionalizantes, etapa chamada de \u201cQualifica\u00e7\u00e3o profissional\u201d.<\/p>\n\n\n\n<p>O nome do pr\u00eamio faz refer\u00eancia ao homem condenado pela pr\u00e1tica de roubo que estava ao lado de Jesus no momento da crucifica\u00e7\u00e3o. \u201cDimas, demonstrando muita humildade, teve uma pequena conversa com Jesus, demonstrando arrependimento e pedindo a Jesus que intercedesse por ele. Dimas, ap\u00f3s uma vida de erros, sentiu que tudo poderia ser diferente\u201d, dizem os relatos hist\u00f3ricos e b\u00edblicos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Contribui\u00e7\u00e3o Ascom MPMT<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta quarta-feira (14), o Sistema Famato\/Senar foi homenageado pelo Minist\u00e9rio P\u00fablico de Mato Grosso com o &#8220;2\u00ba Pr\u00eamio Dimas&#8221;, no audit\u00f3rio da sede das Promotorias de Justi\u00e7a de Cuiab\u00e1. O Senar-MT \u00e9 uma das institui\u00e7\u00f5es que contribu\u00edram para a realiza\u00e7\u00e3o do projeto Reconstruindo Sonhos em unidades prisionais de Mato Grosso, no decorrer de [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":562515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[744],"tags":[],"class_list":["post-562514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acao-social"],"acf":[],"author_meta":{"display_name":"Ana Frutuoso","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/ana-frutuoso\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/11\/WhatsApp-Image-2024-11-14-at-18.54.22-300x225.jpeg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/acao-social\/\" class=\"advgb-post-tax-term\">A\u00e7\u00e3o social<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">A\u00e7\u00e3o social<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 1 ano atr\u00e1s","modified":"Atualizado 1 ano atr\u00e1s"},"absolute_dates":{"created":"Publicado em 15 de novembro de 2024","modified":"Atualizado em 15 de novembro de 2024"},"absolute_dates_time":{"created":"Publicado em 15 de novembro de 2024 10:36","modified":"Atualizado em 15 de novembro de 2024 10:51"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/562514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=562514"}],"version-history":[{"count":5,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/562514\/revisions"}],"predecessor-version":[{"id":562521,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/562514\/revisions\/562521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/562515"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=562514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=562514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=562514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}