{"id":543176,"date":"2024-06-28T15:34:19","date_gmt":"2024-06-28T19:34:19","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=543176"},"modified":"2024-07-03T16:52:37","modified_gmt":"2024-07-03T20:52:37","slug":"senar-mt-realiza-pilotagem-do-novo-treinamento-de-promocao-social-de-planejamento-de-cardapio-rural","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2024\/06\/28\/senar-mt-realiza-pilotagem-do-novo-treinamento-de-promocao-social-de-planejamento-de-cardapio-rural\/","title":{"rendered":"Senar-MT \u00a0lan\u00e7a novo treinamento de Promo\u00e7\u00e3o Social: Planejamento de Card\u00e1pio Rural"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) realizou a pilotagem do novo treinamento de Promo\u00e7\u00e3o Social de Planejamento de Card\u00e1pio Rural nos dias 27 e 28 de junho, em Pocon\u00e9. A novidade visa elaborar card\u00e1pios equilibrados e nutritivos, por meio da sele\u00e7\u00e3o e combina\u00e7\u00e3o de diferentes t\u00e9cnicas de preparo, explorando a regionalidade e promovendo o aproveitamento integral dos alimentos.<\/p>\n\n\n\n<p>O curso foi realizado na Fazenda Lagoa Dourada e teve carga hor\u00e1ria de 16 horas. Durante os dois dias, os participantes elaboraram um card\u00e1pio e aprenderam sobre a sa\u00fade e seguran\u00e7a no trabalho em meio ambiente; gest\u00e3o de compras; tipos de contamina\u00e7\u00e3o; import\u00e2ncia da higiene pessoal; planejamento de card\u00e1pios; sele\u00e7\u00e3o da mat\u00e9ria-prima; prepara\u00e7\u00e3o dos alimentos, al\u00e9m da organiza\u00e7\u00e3o e planejamento do trabalho.<\/p>\n\n\n\n<p>Janaina de Fatima da Silva \u00e9 de nobres e conta que trabalha com cozinha se perguntando todos os dias: &#8220;o que cozinhar?&#8221;. Assim, o conhecimento durante o curso ir\u00e1 auxiliar a montar um card\u00e1pio de 15 a 30 dias, facilitando o trabalho do dia a dia.<\/p>\n\n\n\n<p>J\u00e1 Adriana Lu\u00edsa de Souza conta que est\u00e1 gostando do novo curso e que por trabalhar na cozinha j\u00e1 tinha uma no\u00e7\u00e3o do que foi ministrado. &#8220;Mas o aprendizado \u00e9 sembre bom, porque n\u00e3o estamos cozinahndo para a fam\u00edlia ou amigos, mas sim em um local de trabalho. Ent\u00e3o, \u00e9 maravilhoso aprender a combinar bem a alimenta\u00e7\u00e3o&#8221;, disse Adriana. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-1024x570.jpg\" alt=\"\" class=\"wp-image-543200\" style=\"width:416px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-1024x570.jpg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-300x167.jpg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-768x428.jpg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-1536x855.jpg 1536w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-2048x1140.jpg 2048w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_160037-2-150x84.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>Segundo o supervisor da Regional, Rodrigo Gon\u00e7alves, o intuito \u00e9 propor uma mudan\u00e7a de rotina alimentar di\u00e1ria para os funcion\u00e1rios das propriedades rurais, evitando o desperd\u00edcio, gerando economia na compra dos produtos, visto que  propor um card\u00e1pio definido e ter um fluxo di\u00e1rio evita que os alimentos estraguem e as refei\u00e7\u00f5es fiquem repetitivas.<\/p>\n\n\n\n<p>\u201cUm dos apontamentos do produtor rural \u00e9 que, \u00e0s vezes, durante uma semana inteira o mesmo prato se repete de tr\u00eas a quatro vezes. Ter um card\u00e1pio planejado proporciona tamb\u00e9m que o funcion\u00e1rio da propriedade tenha uma alimenta\u00e7\u00e3o variada e balanceada\u201d, explica o supervisor da Regional.<\/p>\n\n\n\n<p>A analista de Produtos Educacionais, Ana Paula da Silva Gon\u00e7alves, est\u00e1 trabalhando na elabora\u00e7\u00e3o do piloto juntamente com o analista de marketing da equipe de Produtos Educacionais, Rafael Dias. Ela explica que a realiza\u00e7\u00e3o de pilotagem do projeto \u00e9 importante para identificar as adequa\u00e7\u00f5es necess\u00e1rias para que o treinamento possa ser disponibilizado e  demandados pelos Sindicatos Rurais ,e  que atenda  os empreendimentos rurais em Mato Grosso.&nbsp;&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-1024x768.jpg\" alt=\"\" class=\"wp-image-543183\" style=\"width:281px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-1024x768.jpg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-300x225.jpg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-768x576.jpg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-1536x1152.jpg 1536w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-2048x1536.jpg 2048w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_140546-1-150x113.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>A nutricionista Bianca Ribeiro de Oliveira, instrutora credenciada pelo Senar-MT desde&nbsp; 2022, participou pela primeira vez de uma pilotagem, conduzindo os participantes em todo processo de aprendizagem.<\/p>\n\n\n\n<p>Segundo Bianca: \u201cA promo\u00e7\u00e3o de uma alimenta\u00e7\u00e3o adequada e saud\u00e1vel, de acordo com a realidade do p\u00fablico rural, com a finalidade de promover sa\u00fade, melhoria do preparo dos alimentos, apresentando diversidade alimentar, uso integral dos alimentos e modos de preparo, \u00e9 importante para a conscientiza\u00e7\u00e3o da alimenta\u00e7\u00e3o saud\u00e1vel para os trabalhadores rurais\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) realizou a pilotagem do novo treinamento de Promo\u00e7\u00e3o Social de Planejamento de Card\u00e1pio Rural nos dias 27 e 28 de junho, em Pocon\u00e9. A novidade visa elaborar card\u00e1pios equilibrados e nutritivos, por meio da sele\u00e7\u00e3o e combina\u00e7\u00e3o de diferentes t\u00e9cnicas de preparo, explorando a regionalidade [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":543179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[865],"tags":[],"class_list":["post-543176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacao-saudavel"],"acf":[],"author_meta":{"display_name":"taylla.rezende","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/taylla-rezende\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/20240627_135846-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/alimentacao-saudavel\/\" class=\"advgb-post-tax-term\">ALIMENTA\u00c7\u00c3O SAUD\u00c1VEL<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ALIMENTA\u00c7\u00c3O SAUD\u00c1VEL<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 28 de junho de 2024","modified":"Atualizado em 3 de julho de 2024"},"absolute_dates_time":{"created":"Publicado em 28 de junho de 2024 15:34","modified":"Atualizado em 3 de julho de 2024 16:52"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/543176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=543176"}],"version-history":[{"count":13,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/543176\/revisions"}],"predecessor-version":[{"id":544211,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/543176\/revisions\/544211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/543179"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=543176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=543176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=543176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}