{"id":538261,"date":"2024-06-07T17:21:46","date_gmt":"2024-06-07T21:21:46","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=538261"},"modified":"2024-06-07T17:30:18","modified_gmt":"2024-06-07T21:30:18","slug":"alunos-da-escola-municipal-do-campo-sao-jose-visitam-campo-de-girassol-da-escola-agricola-ranchao","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2024\/06\/07\/alunos-da-escola-municipal-do-campo-sao-jose-visitam-campo-de-girassol-da-escola-agricola-ranchao\/","title":{"rendered":"Alunos de Escola Municipal visitam campo de girassol da Ranch\u00e3o"},"content":{"rendered":"\n<p>As turmas do 3\u00b0 e 4\u00b0 ano do ensino fundamental da Escola Municipal do Campo S\u00e3o Jos\u00e9 visitaram nesta quinta-feira, 06 de junho, a Escola Agr\u00edcola Ranch\u00e3o do Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso(Senar-MT), localizada em Nova Mutum. A visita visa inserir na rotina dos estudantes a educa\u00e7\u00e3o sobre a cultura do girassol, os polinizadores e sua import\u00e2ncia para o meio ambiente.<\/p>\n\n\n\n<p>Acompanhados das professoras Jocieli Carnoski e Gon\u00e7alina Auxiliadora da Concei\u00e7\u00e3o, os alunos fizeram um tour pelo campo de girassol da Ranch\u00e3o atrav\u00e9s dos projetos Uni\u00e3o Faz a Vida e Abelhas e Girassol: Empoderando Comunidades Rurais com Agricultura Sustent\u00e1vel.<\/p>\n\n\n\n<p>Assim, puderam investigar a cultura do girassol, incluindo seu cultivo e sua capacidade de atrair abelhas produtoras de mel, enfatizando a import\u00e2ncia da preserva\u00e7\u00e3o desses polinizadores para o meio ambiente. Tamb\u00e9m conhecer os m\u00faltiplos benef\u00edcios do girassol para a agricultura, a ind\u00fastria e a alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Segundo o gerente de Educa\u00e7\u00e3o Formal do Senar-MT, Marcos Medeiros, a institui\u00e7\u00e3o est\u00e1 sempre aberta \u00e0s  escolas de Nova Mutum para apresentar \u00e0s crian\u00e7as e adolescentes um relacionamento com o agroneg\u00f3cio nas rotinas das atividades escolares.<\/p>\n\n\n\n<p>\u201cO Senar-MT tem a satisfa\u00e7\u00e3o em oferecer mais conhecimento para os alunos do ensino fundamental e ensino m\u00e9dio de Nova Mutum. Isso proporciona conhecimento sobre a realidade do agro, das atividades, sobre de onde vem o alimento que chega em suas mesas. Ent\u00e3o estaremos sempre fomentando esse tipo de atividade\u201d, disse o gerente de Educa\u00e7\u00e3o Formal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As turmas do 3\u00b0 e 4\u00b0 ano do ensino fundamental da Escola Municipal do Campo S\u00e3o Jos\u00e9 visitaram nesta quinta-feira, 06 de junho, a Escola Agr\u00edcola Ranch\u00e3o do Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso(Senar-MT), localizada em Nova Mutum. A visita visa inserir na rotina dos estudantes a educa\u00e7\u00e3o sobre a cultura do girassol, [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":538262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[849],"tags":[],"class_list":["post-538261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-e-sustentabilidade"],"acf":[],"author_meta":{"display_name":"taylla.rezende","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/taylla-rezende\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/06\/WhatsApp-Image-2024-06-06-at-17.09.47-300x225.jpeg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/educacao-e-sustentabilidade\/\" class=\"advgb-post-tax-term\">EDUCA\u00c7\u00c3O E SUSTENTABILIDADE<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">EDUCA\u00c7\u00c3O E SUSTENTABILIDADE<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 7 de junho de 2024","modified":"Atualizado em 7 de junho de 2024"},"absolute_dates_time":{"created":"Publicado em 7 de junho de 2024 17:21","modified":"Atualizado em 7 de junho de 2024 17:30"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/538261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=538261"}],"version-history":[{"count":6,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/538261\/revisions"}],"predecessor-version":[{"id":538314,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/538261\/revisions\/538314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/538262"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=538261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=538261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=538261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}