{"id":527570,"date":"2024-04-29T07:53:31","date_gmt":"2024-04-29T11:53:31","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/?p=527570"},"modified":"2024-04-29T07:54:13","modified_gmt":"2024-04-29T11:54:13","slug":"produtores-de-brasnorte-evidenciam-aumento-de-mais-de-70-em-producao-apos-assistencia-tecnica-do-senar-mt","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2024\/04\/29\/produtores-de-brasnorte-evidenciam-aumento-de-mais-de-70-em-producao-apos-assistencia-tecnica-do-senar-mt\/","title":{"rendered":"Produtores de Brasnorte evidenciam aumento de mais de 70% em produ\u00e7\u00e3o ap\u00f3s assist\u00eancia t\u00e9cnica do Senar-MT"},"content":{"rendered":"\n<p>Ap\u00f3s tr\u00eas anos de Assist\u00eancia T\u00e9cnica e Gerencial (ATeG) da cadeia de bovinocultura de corte de Brasnorte, a Produ\u00e7\u00e3o Anual de Carne vendida em 2023 aumentou em 76,36% em rela\u00e7\u00e3o a 2022. Per\u00edodo este, que um grupo de 15 produtores rurais alcan\u00e7ou uma venda significativa de bezerros, totalizando 22.862,33 Kg\/ano. No entanto, no ano passado este n\u00famero quase dobrou, alcan\u00e7ando 40.324,99 Kg\/ano, evidenciando um crescimento expressivo na comercializa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Durante os 36 meses de assist\u00eancia t\u00e9cnica, por meio da ATeG, foram implementadas metodologias nas propriedades com pr\u00e1ticas mais eficientes, com melhores estrat\u00e9gias de manejo e de mercado.<\/p>\n\n\n\n<p>Segundo dados do Sistema de Gest\u00e3o da Assist\u00eancia T\u00e9cnica e Gerencial (Sisateg), outro aspecto relevante foi a an\u00e1lise da Taxa de Retorno do Capital, tanto com terra quanto sem-terra. Em 2022, a taxa de retorno do capital sem-terra foi de 33,74%, destacando a efic\u00e1cia dos investimentos realizados. Embora tenha reduzido em 2023, as taxas de retorno permaneceram significativamente positivas, demonstrando a viabilidade econ\u00f4mica das atividades desenvolvidas pelo grupo.<\/p>\n\n\n\n<p>Segundo o gerente de ATeG, Bruno de Faria, esses resultados positivos refletem no comprometimento dos produtores e o engajamento do t\u00e9cnico de campo, Eder Faccin, que, com sua expertise e orienta\u00e7\u00e3o, contribuiu para o fortalecimento e aprimoramento das pr\u00e1ticas de manejo e gest\u00e3o nas propriedades rurais de Brasnorte. \u201cEssa hist\u00f3ria de sucesso destaca o valor da assist\u00eancia t\u00e9cnica e gerencial como um instrumento essencial para o desenvolvimento sustent\u00e1vel da agricultura e pecu\u00e1ria\u201d, completou o gerente de ATeG.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"500\" src=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/WhatsApp-Image-2024-04-26-at-16.30.35-1024x500.jpeg\" alt=\"\" class=\"wp-image-527572\" style=\"width:461px;height:auto\" srcset=\"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/WhatsApp-Image-2024-04-26-at-16.30.35-1024x500.jpeg 1024w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/WhatsApp-Image-2024-04-26-at-16.30.35-300x147.jpeg 300w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/WhatsApp-Image-2024-04-26-at-16.30.35-768x375.jpeg 768w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/WhatsApp-Image-2024-04-26-at-16.30.35-150x73.jpeg 150w, https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/WhatsApp-Image-2024-04-26-at-16.30.35.jpeg 1474w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>Para Eder, o encerramento das atividades e seus resultados \u00e9 gratificante para seu trabalho. \u201cUsar nosso conhecimento para ajudar os outros e ver que conseguimos transformar vidas, trazer esperan\u00e7a para as pessoas do meio rural. E gra\u00e7as aos produtores, conseguimos alcan\u00e7ar objetivos, pois estavam dispostos a tra\u00e7ar caminhos diferentes para juntos alcan\u00e7armos as metas\u201d, disse o t\u00e9cnico de campo.<\/p>\n\n\n\n<p>Ainda segundo Eder, as principais queixas na regi\u00e3o eram de n\u00e3o conseguir um valor bom nos animais, a demora para estarem prontos para venda, em rela\u00e7\u00e3o \u00e0s pastagens, demoravam muito para retornar, al\u00e9m da falta de alimenta\u00e7\u00e3o para os animais durante a seca e dificuldades com a nutri\u00e7\u00e3o e gest\u00e3o financeira.<\/p>\n\n\n\n<p>Durante o ciclo de atendimentos foram realizados cuidados com o solo, manejo de pastagem, suplementa\u00e7\u00e3o adequada para cada fase de vida dos animais, manejo com foco na \u00e9poca de seca, silagens adequadas para cada realidade, \u00e1gua de qualidade, manejos sanit\u00e1rios, gen\u00e9tica dos animais, manejo com bezerros, gest\u00e3o econ\u00f4mica financeira e dos animais, dentre outros.<\/p>\n\n\n\n<p>\u201cOs atendimentos foram voltados na busca de suprir as necessidades individuais de cada propriedade, de cada produtor, pois temos que entender que mesmo que sejam vizinhos de cerca s\u00e3o realidades totalmente diferentes\u201d, completou o t\u00e9cnico de campo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s tr\u00eas anos de Assist\u00eancia T\u00e9cnica e Gerencial (ATeG) da cadeia de bovinocultura de corte de Brasnorte, a Produ\u00e7\u00e3o Anual de Carne vendida em 2023 aumentou em 76,36% em rela\u00e7\u00e3o a 2022. Per\u00edodo este, que um grupo de 15 produtores rurais alcan\u00e7ou uma venda significativa de bezerros, totalizando 22.862,33 Kg\/ano. No entanto, no ano passado [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":527583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[818],"tags":[],"class_list":["post-527570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bovinocultura-de-corte"],"acf":[],"author_meta":{"display_name":"taylla.rezende","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/taylla-rezende\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2024\/04\/gado-nelore-olhando-para-a-camera-no-curral-vaca-branca-300x199.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/balanco\/bovinocultura-de-corte\/\" class=\"advgb-post-tax-term\">BOVINOCULTURA DE CORTE<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">BOVINOCULTURA DE CORTE<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 29 de abril de 2024","modified":"Atualizado em 29 de abril de 2024"},"absolute_dates_time":{"created":"Publicado em 29 de abril de 2024 07:53","modified":"Atualizado em 29 de abril de 2024 07:54"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/527570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=527570"}],"version-history":[{"count":8,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/527570\/revisions"}],"predecessor-version":[{"id":527983,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/527570\/revisions\/527983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/527583"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=527570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=527570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=527570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}