{"id":11370,"date":"2013-11-05T11:07:06","date_gmt":"2013-11-05T13:07:06","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/11\/05\/soja-brasil-visita-campo-verde-e-jaciara-nesta-terca-5\/"},"modified":"2013-11-05T11:07:06","modified_gmt":"2013-11-05T13:07:06","slug":"soja-brasil-visita-campo-verde-e-jaciara-nesta-terca-5","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/11\/05\/soja-brasil-visita-campo-verde-e-jaciara-nesta-terca-5\/","title":{"rendered":"Soja Brasil visita Campo Verde e Jaciara nesta ter\u00e7a (5)"},"content":{"rendered":"<p>\nNesta ter\u00e7a-feira (5) a Expedi\u00e7\u00e3o Soja Brasil, realizada em Mato Grosso em parceria com o Servi\u00e7o Nacional de Aprendizagem Rural (Senar-MT) e Canal Rural, trabalha nos munic\u00edpios de Campo Verde e Jaciara. Nesta segunda semana da viagem a equipe j\u00e1 visitou Alto Gar\u00e7as e Rondon\u00f3polis. Na quarta (6) passa por Primavera do Leste, na quinta (7) estar\u00e1 em Nova Xavantina e \u00c1gua Boa e na sexta (8) em Canarana e Quer\u00eancia.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nAo todo, a equipe vai percorrer 40 mil quil\u00f4metros passando por treze estados. O objetivo da longa viagem \u00e9 promover uma consultoria especializada para ajudar o Brasil a vencer os desafios e se manter no patamar de lideran\u00e7a da produ\u00e7\u00e3o mundial de soja.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nEm Mato Grosso, a Expedi\u00e7\u00e3o conta com a equipe do Senar-MT formada pelo analista Eduardo Silveira, pela jornalista Amanda Sampaio e pelos supervisores regionais da entidade que acompanham as entrevistas e contribuem com dado da regi\u00e3o.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nEm Sorriso, o supervisor regional do Senar-MT, Dorvalino Kasinski fala sobre o trabalho realizado pela entidade para ajudar os produtores a combater as pragas e doen\u00e7as nas lavouras de soja de Mato Grosso. Confira a mat\u00e9ria completa no link &#8211;<br \/>\n<a href=\"http:\/\/ruralbr.co\/1ef2cwD\" target=\"_blank\" rel=\"noopener\">http:\/\/ruralbr.co\/1ef2cwD<\/a><\/p>\n<p>\n\u00a0<\/p>\n<p>\nVoc\u00ea pode assistir \u00e0s not\u00edcias da Expedi\u00e7\u00e3o Soja Brasil diariamente no programa Mercado e Companhia do Canal Rural, nas edi\u00e7\u00f5es de onze e vinte, e \u00e0 noite, a partir das dezessete e trinta. Visite o site especial do projeto <a href=\"http:\/\/www.projetosojabrasil.com.br\/\">www.projetosojabrasil.com.br<\/a> e fique por dentro das not\u00edcias e bastidores.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/senar_mt\">@senar_mt <\/a>e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\">www.facebook.com\/SenarMt<\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso, atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira (5) a Expedi\u00e7\u00e3o Soja Brasil, realizada em Mato Grosso em parceria com o Servi\u00e7o Nacional de Aprendizagem Rural (Senar-MT) e Canal Rural, trabalha nos munic\u00edpios de Campo Verde e Jaciara. Nesta segunda semana da viagem a equipe j\u00e1 visitou Alto Gar\u00e7as e Rondon\u00f3polis. Na quarta (6) passa por Primavera do Leste, na quinta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/11\/05112013110649-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 5 de novembro de 2013","modified":"Atualizado em 5 de novembro de 2013"},"absolute_dates_time":{"created":"Publicado em 5 de novembro de 2013 11:07","modified":"Atualizado em 5 de novembro de 2013 11:07"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11370"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5228"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}