{"id":11364,"date":"2013-10-29T11:39:54","date_gmt":"2013-10-29T13:39:54","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/29\/comercializacao-de-soja-e-etanol-de-cereais-e-o-assunto-em-campos-de-julio\/"},"modified":"2013-10-29T11:39:54","modified_gmt":"2013-10-29T13:39:54","slug":"comercializacao-de-soja-e-etanol-de-cereais-e-o-assunto-em-campos-de-julio","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/29\/comercializacao-de-soja-e-etanol-de-cereais-e-o-assunto-em-campos-de-julio\/","title":{"rendered":"Comercializa\u00e7\u00e3o de soja e etanol de cereais \u00e9 o assunto em Campos de Julio"},"content":{"rendered":"<p>\nA Expedi&ccedil;&atilde;o Soja Brasil iniciou suas atividades em Mato Grosso nesta segunda (28) pelo munic&iacute;pio de Campos de J&uacute;lio. &Agrave;s 17h20, a rep&oacute;rter Kellen Severo entrevistou ao vivo o presidente do Sindicato dos Produtores Rurais&nbsp; do munic&iacute;pio, Ademir Rostirolla, para o programa Mercado &amp; Cia.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nO produtor falou sobre aumento da produ&ccedil;&atilde;o de soja, controle de pragas (Helicoverpa e Ferrugem Asi&aacute;tica) e baixa comercializa&ccedil;&atilde;o antecipada da soja pelos produtores do munic&iacute;pio.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nSegundo ele, na safra 2013\/14, ser&atilde;o produzidas 500 mil toneladas de soja em Campos de J&uacute;lio, o que equivale a 150 mil toneladas a mais que na safra passada.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nAt&eacute; o momento, 40% da produ&ccedil;&atilde;o foi comercializada antecipadamente. No mesmo per&iacute;odo do ano passado, 65% da safra j&aacute; havia sido negociada. No entanto, o presidente tem uma vis&atilde;o positiva da comercializa&ccedil;&atilde;o do gr&atilde;o. &quot;Os fundamentos econ&ocirc;micos que apontavam a queda do pre&ccedil;o da safra de soja n&atilde;o se sustentam e temos comprador. Acredito que os produtores estejam esperando para ver o que acontece com a safra nos Estados Unidos&quot;.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\n<span style=\"font-size:14px;\"><strong>ETANOL <\/strong><\/span>&#8211; &Agrave;s 18 horas, foi a vez do diretor da Usimat,S&eacute;rgio Barbieri, conceder entrevista ao vivo para o programa Rural Not&iacute;cias sobre o in&iacute;cio da produ&ccedil;&atilde;o de etanol de milho e sorgo e DDG (Dried Distillers Grains with Solubles &#8211; um subproduto da produ&ccedil;&atilde;o do etanol de milho) como alternativa &agrave; alta produ&ccedil;&atilde;o de milho no Estado.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nCom investimentos de R$ 47 milh&otilde;es, a usina, que j&aacute; produz 64 milh&otilde;es de litros de etanol a partir do processamento de 800 mil toneladas (ton) de cana de a&ccedil;&uacute;car por ano, passar&aacute; a operar tamb&eacute;m durante a entressafra, entre os meses de dezembro a mar&ccedil;o, processando 90 mil toneladas dos cereais nesta safra. Esse volume de cereais gerar&aacute; 31milh&otilde;es de litros de etanol e 16 mil toneladas de DDG. A Usimat em parceria com o Senar-MT j&aacute; qualificou 410 pessoas.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nAl&eacute;m de Campos de J&uacute;lio, os cereais ser&atilde;o comprados dos munic&iacute;pios de Campo Novo do Parecis e Sapezal. Enquanto a empresa pode comercializar o etanol para consumo interno e tamb&eacute;m Rond&ocirc;nia e Amaz&ocirc;nia, Barbieri informa que o DDG j&aacute; tem mercado certo na regi&atilde;o oeste do Estado, onde est&atilde;o munic&iacute;pios como C&aacute;ceres e Pontes e Lacerda, em que predomina a pecu&aacute;ria.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nDentre os v&aacute;rios benef&iacute;cios citados pelo diretor, est&aacute; o prolongamento do per&iacute;odo de safra, o que gerou aumento de 20% do quadro de funcion&aacute;rios na usina, que deixaram de ter um emprego sazonal para ter trabalho ao longo de todo o ano. &quot;Com o etanol de cereais, n&atilde;o precisamos nos preocupar em importar trabalhadores de outros estados no in&iacute;cio de safra cana, pois eles podem se fixar no munic&iacute;pio e assim podemos investir mais em qualifica&ccedil;&atilde;o da m&atilde;o de obra, pois ela permanece na empresa&quot;, ressalta.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nAtualmente, o corte de cana &eacute; feito 40% atrav&eacute;s de mecaniza&ccedil;&atilde;o e os outros 60% manualmente.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nAssista &agrave;s entrevistas do dia 28\/10, de Campos de J&uacute;lio, no site do Canal Rural:<\/p>\n<p>\n<strong>Ademir Rostirolla<\/strong>: <a href=\"http:\/\/videos.ruralbr.com.br\/canalrural\/video\/mercado-e-companhia\/2013\/10\/presidente-sindicato-rural-campos-julio-fala-sobre-producao-soja\/47701\/\">http:\/\/videos.ruralbr.com.br\/canalrural\/video\/mercado-e-companhia\/2013\/10\/presidente-sindicato-rural-campos-julio-fala-sobre-producao-soja\/47701\/<\/a><\/p>\n<p>\n<strong>S&eacute;rgio Barbieri<\/strong>: <a href=\"http:\/\/videos.ruralbr.com.br\/canalrural\/video\/rural-noticias\/2013\/10\/campos-julio-pioneira-utilizacao-milho-para-fabricacao-etanol\/47708\/\">http:\/\/videos.ruralbr.com.br\/canalrural\/video\/rural-noticias\/2013\/10\/campos-julio-pioneira-utilizacao-milho-para-fabricacao-etanol\/47708\/<\/a><\/p>\n<p>\n&nbsp;<\/p>\n<p>\n<strong>PROGRAMA&Ccedil;&Atilde;O <\/strong>&ndash; Nesta ter&ccedil;a-feira&nbsp; (29), &nbsp;o Projeto Soja Brasil entrevista produtores de Campo Novo do Parecis &agrave;s 11h20 (hor&aacute;rio de Mato Grosso), no programa Mercado &amp; Cia. O programa Mercado &amp; Cia das 17h20 e Rural Not&iacute;cias das 18h exibem entrevistas de produtores de Tangar&aacute; da Serra.<\/p>\n<p>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Expedi&ccedil;&atilde;o Soja Brasil iniciou suas atividades em Mato Grosso nesta segunda (28) pelo munic&iacute;pio de Campos de J&uacute;lio. &Agrave;s 17h20, a rep&oacute;rter Kellen Severo entrevistou ao vivo o presidente do Sindicato dos Produtores Rurais&nbsp; do munic&iacute;pio, Ademir Rostirolla, para o programa Mercado &amp; Cia. &nbsp; O produtor falou sobre aumento da produ&ccedil;&atilde;o de soja, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/10\/29102013113933-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 29 de outubro de 2013","modified":"Atualizado em 29 de outubro de 2013"},"absolute_dates_time":{"created":"Publicado em 29 de outubro de 2013 11:39","modified":"Atualizado em 29 de outubro de 2013 11:39"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11364"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5216"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}