{"id":11360,"date":"2013-10-24T10:53:39","date_gmt":"2013-10-24T12:53:39","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/24\/viagem-do-soja-brasil-comeca-neste-domingo-27\/"},"modified":"2013-10-24T10:53:39","modified_gmt":"2013-10-24T12:53:39","slug":"viagem-do-soja-brasil-comeca-neste-domingo-27","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/24\/viagem-do-soja-brasil-comeca-neste-domingo-27\/","title":{"rendered":"Viagem do Soja Brasil come\u00e7a neste domingo (27)"},"content":{"rendered":"<p>\nA maior expedi\u00e7\u00e3o por lavouras de soja do pa\u00eds come\u00e7a neste domingo (27), em Vilhena e vai percorrer at\u00e9 mar\u00e7o de 2014 mais de 40 mil quil\u00f4metros. As equipes formadas por jornalistas, pesquisadores, especialistas e analistas de mercado passar\u00e3o por 13 estados brasileiros. A previs\u00e3o \u00e9 de que estes profissionais fiquem cerca de cinco meses na estrada. O objetivo \u00e9 conferir de perto o desenvolvimento de mais uma safra, que promete n\u00fameros recordes.<\/p>\n<p>\n\u00a0<br \/>\nA expedi\u00e7\u00e3o faz parte do Projeto Soja Brasil, uma realiza\u00e7\u00e3o do Canal Rural, da Associa\u00e7\u00e3o Brasileira dos Produtores de Soja (Aprosoja Brasil) e do Servi\u00e7o Nacional de Aprendizagem Rural em Mato Grosso (Senar-MT). \u00a0O p\u00fablico poder\u00e1 acompanhar toda a viagem \u00a0nos sites <a href=\"http:\/\/WWW.senarmt.org.br\">WWW.senarmt.org.br<\/a> \u00a0e no <a href=\"http:\/\/sojabrasil.ruralbr.com.br\">http:\/\/sojabrasil.ruralbr.com.br<\/a>. \u00a0E quem estiver interessado em conhecer um pouco dos bastidores da viagem do Projeto Soja Brasil\u00a0 pode acessar o blog da Soja Brasil &#8211; http:\/\/blogs.ruralbr.com.br\/sojabrasil.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso,\u00a0 atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT).<\/p>\n<p>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A maior expedi\u00e7\u00e3o por lavouras de soja do pa\u00eds come\u00e7a neste domingo (27), em Vilhena e vai percorrer at\u00e9 mar\u00e7o de 2014 mais de 40 mil quil\u00f4metros. As equipes formadas por jornalistas, pesquisadores, especialistas e analistas de mercado passar\u00e3o por 13 estados brasileiros. A previs\u00e3o \u00e9 de que estes profissionais fiquem cerca de cinco meses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/10\/24102013105257-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 24 de outubro de 2013","modified":"Atualizado em 24 de outubro de 2013"},"absolute_dates_time":{"created":"Publicado em 24 de outubro de 2013 10:53","modified":"Atualizado em 24 de outubro de 2013 10:53"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11360"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5208"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}