{"id":11357,"date":"2013-10-21T13:29:00","date_gmt":"2013-10-21T15:29:00","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/21\/pedro-taques-diz-que-mato-grosso-perde-um-lider-comprometido-com-o-estado\/"},"modified":"2013-10-21T13:29:00","modified_gmt":"2013-10-21T15:29:00","slug":"pedro-taques-diz-que-mato-grosso-perde-um-lider-comprometido-com-o-estado","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/21\/pedro-taques-diz-que-mato-grosso-perde-um-lider-comprometido-com-o-estado\/","title":{"rendered":"Pedro Taques diz que Mato Grosso perde um l\u00edder comprometido com o Estado"},"content":{"rendered":"<p>\n<span style=\"background-color: rgba(255, 255, 255, 0);\">O senador Pedro Taques (PDT-MT) recebe com pesar a not&iacute;cia do falecimento do deputado federal Homero Pereira, ocorrido no final da manh&atilde; deste domingo (20). O parlamentar lamenta o falecimento deste pol&iacute;tico e companheiro de bancada que, h&aacute; meses, lutava contra um c&acirc;ncer no est&ocirc;mago.<\/span><\/p>\n<p>\n<br \/>\n<span style=\"background-color: rgba(255, 255, 255, 0);\">&quot;L&iacute;der pol&iacute;tico comprometido com o cidad&atilde;o de Mato Grosso, Homero foi um dos protagonistas no processo de consolida&ccedil;&atilde;o do Estado enquanto pot&ecirc;ncia econ&ocirc;mica. Mato Grosso e o Brasil perdem muito com a partida precoce deste grande parlamentar&quot;, afirmou Pedro Taques.<\/span><\/p>\n<p><span style=\"background-color: rgba(255, 255, 255, 0);\">O senador pelo PDT ressalta que Homero Pereira deixa sua marca como um bom combatente &#8211; seja lutando politicamente, seja como um cidad&atilde;o que enfrentou o c&acirc;ncer at&eacute; o &uacute;ltimo momento de sua vida.<\/span><\/p>\n<p><span style=\"background-color: rgba(255, 255, 255, 0);\">&quot;Al&eacute;m de pol&iacute;tico dedicado e combativo, seu lado humano &eacute; um grande legado que ele nos deixa. Neste momento de dor e tristeza, estendo a todos os familiares os votos de conforto&quot;.<\/span><\/p>\n<p>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O senador Pedro Taques (PDT-MT) recebe com pesar a not&iacute;cia do falecimento do deputado federal Homero Pereira, ocorrido no final da manh&atilde; deste domingo (20). O parlamentar lamenta o falecimento deste pol&iacute;tico e companheiro de bancada que, h&aacute; meses, lutava contra um c&acirc;ncer no est&ocirc;mago. &quot;L&iacute;der pol&iacute;tico comprometido com o cidad&atilde;o de Mato Grosso, Homero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/10\/21102013012849-300x226.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 21 de outubro de 2013","modified":"Atualizado em 21 de outubro de 2013"},"absolute_dates_time":{"created":"Publicado em 21 de outubro de 2013 13:29","modified":"Atualizado em 21 de outubro de 2013 13:29"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11357"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5202"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}