{"id":11351,"date":"2013-10-16T11:58:47","date_gmt":"2013-10-16T14:58:47","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/16\/equipes-do-circuito-tecnologico-visitam-a-regiao-norte-e-oeste-nesta-semana\/"},"modified":"2013-10-16T11:58:47","modified_gmt":"2013-10-16T14:58:47","slug":"equipes-do-circuito-tecnologico-visitam-a-regiao-norte-e-oeste-nesta-semana","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/10\/16\/equipes-do-circuito-tecnologico-visitam-a-regiao-norte-e-oeste-nesta-semana\/","title":{"rendered":"Equipes do Circuito Tecnol\u00f3gico visitam a regi\u00e3o norte e oeste nesta semana"},"content":{"rendered":"<p>\nO trabalho das equipes do Circuito Tecnol\u00f3gico que come\u00e7ou na \u00faltima segunda-feira (14), com o in\u00edcio da viagem,\u00a0 \u00e9 intenso.\u00a0 A \u00a0expedi\u00e7\u00e3o \u00e9 realizada pela \u00a0Aprosoja, \u00a0Servi\u00e7o de Aprendizagem Rural (Senar\/MT) e tem como patrocinadores\u00a0 Basf, Dow Agrosciences e Bayer.\u00a0 At\u00e9 o final de outubro as equipes\u00a0 far\u00e3o um raio-x da safra de soja 2013\/14.\u00a0 Nas visitas os profissionais questionam os produtores sobre qualidade de sementes, fertilizantes, manejo de pragas, uso de maquin\u00e1rios, gest\u00e3o, m\u00e3o de obra, infraestrutura e outros.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO grupo \u00e9 formado por oito equipes que visitar\u00e3o cerca de 600 propriedades nas regi\u00f5es produtoras de soja. Fazem parte das equipes profissionais da \u00e1rea t\u00e9cnica da Aprosoja, Senar,\u00a0 estudantes do curso de Agronomia e consultores da Empresa Brasileira de Pesquisa (Embrapa), Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea) e da Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria de Mato Grosso (Famato). Nesta primeira semana as equipes visitam\u00a0 propriedades nas \u00a0regi\u00f5es Norte e Oeste.<\/p>\n<p>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O trabalho das equipes do Circuito Tecnol\u00f3gico que come\u00e7ou na \u00faltima segunda-feira (14), com o in\u00edcio da viagem,\u00a0 \u00e9 intenso.\u00a0 A \u00a0expedi\u00e7\u00e3o \u00e9 realizada pela \u00a0Aprosoja, \u00a0Servi\u00e7o de Aprendizagem Rural (Senar\/MT) e tem como patrocinadores\u00a0 Basf, Dow Agrosciences e Bayer.\u00a0 At\u00e9 o final de outubro as equipes\u00a0 far\u00e3o um raio-x da safra de soja 2013\/14.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/10\/16102013115814-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 16 de outubro de 2013","modified":"Atualizado em 16 de outubro de 2013"},"absolute_dates_time":{"created":"Publicado em 16 de outubro de 2013 11:58","modified":"Atualizado em 16 de outubro de 2013 11:58"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11351"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5190"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}