{"id":11331,"date":"2013-09-23T17:24:54","date_gmt":"2013-09-23T20:24:54","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/09\/23\/novo-treinamento-ja-tem-as-proximas-turmas-programadas\/"},"modified":"2013-09-23T17:24:54","modified_gmt":"2013-09-23T20:24:54","slug":"novo-treinamento-ja-tem-as-proximas-turmas-programadas","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/09\/23\/novo-treinamento-ja-tem-as-proximas-turmas-programadas\/","title":{"rendered":"Novo treinamento j\u00e1 tem as pr\u00f3ximas turmas programadas"},"content":{"rendered":"<p>\nUm sucesso. Foi assim que o presidente do Sindicato Rural de Sinop, Leonildo Barei definiu o primeiro treinamento sobre agricultura de precis\u00e3o realizado pelo Sindicato Rural de Sinop em parceria com o Servi\u00e7o Nacional de Aprendizagem Rural (Senar-MT), na \u00faltima semana. &#8220;A demanda nesta \u00e1rea \u00e9 grande em Sinop e j\u00e1 estamos programando o pr\u00f3ximo para o m\u00eas de novembro&#8221;.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nLeonildo explica que em outubro os produtores rurais estar\u00e3o envolvidos com o plantio da soja e, por isso, n\u00e3o t\u00eam condi\u00e7\u00f5es de fazer nenhum tipo de treinamento ou curso neste per\u00edodo. &#8220;Em fun\u00e7\u00e3o disso, s\u00f3 poderemos programar para o in\u00edcio de novembro quando acabar o plantio&#8221;.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO supervisor regional do Senar-MT, Dorvalino Karlinski acrescenta que esta primeira turma de Sinop foi bastante heterog\u00eanea, mas que o instrutor Carlos Danielli utilizou uma metodologia que facilitou o entendimento para todos. Dorvalino ressalta que os produtores rurais interessados em fazer o curso de agricultura de precis\u00e3o devem procurar o sindicato rural de seu munic\u00edpio.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nTecnologia de Precis\u00e3o em M\u00e1quinas Agr\u00edcolas \u00e9 um treinamento novo do Senar-MT com dura\u00e7\u00e3o de 40 horas. O conte\u00fado inclui assuntos como seguran\u00e7a no trabalho, \u00e9tica, cidadania e meio ambiente. Os alunos tamb\u00e9m aprendem a trabalhar com o computador de bordo, banco de dados de agricultura de precis\u00e3o, piloto autom\u00e1tico, coleta de dados e ainda v\u00e3o estudar v\u00e1rios outros equipamentos relacionados \u00e0 \u00e1rea.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nLeonildo acrescenta que os operadores de m\u00e1quinas precisam aprender a trabalhar com a tecnologia embarcada como, por exemplo, o GPS, opera\u00e7\u00e3o e instala\u00e7\u00e3o da barra de luzes, piloto autom\u00e1tico e controle autom\u00e1tico de se\u00e7\u00f5es. &#8220;A qualifica\u00e7\u00e3o oferecida por este novo treinamento do Senar-MT atende perfeitamente nossas necessidades&#8221;.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO analista em educa\u00e7\u00e3o rural do Senar-MT, Alis Firmino conta que o treinamento de tecnologia de precis\u00e3o em m\u00e1quinas agr\u00edcolas tamb\u00e9m ser\u00e1 realizado no munic\u00edpio de Sorriso, a partir de 21 de outubro, e em Alto Taquari a partir de 28 de outubro. &#8220;Campo Verde tamb\u00e9m est\u00e1 na lista, mas ainda sem data prevista&#8221;.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nEstes treinamentos s\u00e3o realizados pelos sindicatos rurais de cada munic\u00edpio em parceria com o Senar-MT. Os interessados em mais informa\u00e7\u00f5es sobre os novos treinamentos oferecidos pelo Senar-MT devem acessar o site <a href=\"http:\/\/www.senarmt.org.br\" target=\"_blank\" rel=\"noopener\">www.senarmt.org.br<\/a> ou entrar em contato com o Sindicato Rural de seu munic\u00edpio.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga @senar_mt e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso, atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT).<\/p>\n<p>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um sucesso. Foi assim que o presidente do Sindicato Rural de Sinop, Leonildo Barei definiu o primeiro treinamento sobre agricultura de precis\u00e3o realizado pelo Sindicato Rural de Sinop em parceria com o Servi\u00e7o Nacional de Aprendizagem Rural (Senar-MT), na \u00faltima semana. &#8220;A demanda nesta \u00e1rea \u00e9 grande em Sinop e j\u00e1 estamos programando o pr\u00f3ximo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/09\/23092013052357-300x207.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 23 de setembro de 2013","modified":"Atualizado em 23 de setembro de 2013"},"absolute_dates_time":{"created":"Publicado em 23 de setembro de 2013 17:24","modified":"Atualizado em 23 de setembro de 2013 17:24"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11331"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5150"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}