{"id":11324,"date":"2013-09-16T09:59:09","date_gmt":"2013-09-16T12:59:09","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/09\/16\/cursos-de-qualificacao-transformam-a-vida-de-vaqueiros\/"},"modified":"2013-09-16T09:59:09","modified_gmt":"2013-09-16T12:59:09","slug":"cursos-de-qualificacao-transformam-a-vida-de-vaqueiros","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/09\/16\/cursos-de-qualificacao-transformam-a-vida-de-vaqueiros\/","title":{"rendered":"Cursos de qualifica\u00e7\u00e3o transformam a vida de vaqueiros"},"content":{"rendered":"<p>\nEnquanto sela o cavalo com cuidado e paci\u00eancia, o vaqueiro Erasmo Aparecido Pereira Leite, de 44 anos fala sobre as transforma\u00e7\u00f5es que ocorreram em sua vida nos \u00faltimos tempos. Segundo ele, depois que fez os cursos gratuitos oferecidos pelo Sindicado Rural de Ros\u00e1rio Oeste em parceria com Servi\u00e7o Nacional de Aprendizagem Rural (Senar-MT) sua renda mensal melhorou e a produtividade no trabalho aumentou.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO analista de educa\u00e7\u00e3o rural, Wlademiro Neto, diz que o Senar-MT oferece v\u00e1rios cursos e treinamentos para os profissionais do setor de equinos. Para a segunda quinzena de setembro, est\u00e3o previstos v\u00e1rios eventos para os munic\u00edpios de Colniza, Ribeir\u00e3ozinho, Sinop, S\u00e3o Felix do Araguaia, Dom Aquino, Aripuan\u00e3, Porto Estrela e v\u00e1rios outros.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nNo curr\u00edculo de Erasmo j\u00e1 constam os cursos de doma racional, r\u00e9deas, casqueamento e ferrageamento de equ\u00eddeos. &#8220;Quero fazer tudo o que \u00e9 oferecido pelo Sindicato Rural\u00a0em parceria com o Senar-MT&#8221;. Erasmo conta que antes de fazer os cursos levava em m\u00e9dia dois anos para domar um cavalo. &#8220;Depois dos treinamentos consigo deixar o animal pronto para a lida no campo\u00a0 em 90 dias&#8221;. J\u00e1 quando o assunto \u00e9 dinheiro, Erasmo diz que ganha em m\u00e9dia um sal\u00e1rio m\u00ednimo (R$ 678), por m\u00eas, por cada cavalo que doma.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nAssim como Erasmo, o irm\u00e3o Pedro Paulo Pereira Leite, de 45 anos, tamb\u00e9m \u00e9 vaqueiro e se profissionalizou fazendo os cursos oferecidos pelo Sindicato Rural em parceria com o Senar-MT.\u00a0 Atualmente cuida de tr\u00eas fazendas. &#8220;Os treinamentos transformaram a vida de todos na minha fam\u00edlia&#8221;, ressalta Erasmo.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nInstrutor do setor de equinos, Heitor Violin Brandt ministra em m\u00e9dia quatro cursos por m\u00eas em todos os cantos e recantos de Mato Grosso. Ele conta que o respeito e a paci\u00eancia s\u00e3o os principais ingredientes para que o homem possa trabalhar em harmonia com o animal. Heitor conta ainda que 60% dos participantes j\u00e1 trabalham no setor. Os outros 40% geralmente s\u00e3o jovens em busca de uma forma\u00e7\u00e3o profissional. Segundo Heitor, os cursos ministrados pelos Sindicatos Rurais em parceria com o Senar-MT qualificam os profissionais deste setor que tem uma demanda bastante elevada.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nA diferen\u00e7a entre a doma racional e a tradicional ou a caipira, como \u00e9 popularmente chamada, \u00e9 que na racional o cavalo \u00e9 tratado com muito respeito e o homem adquire a confian\u00e7a do animal aos poucos. &#8220;A rela\u00e7\u00e3o entre homem e cavalo \u00e9 de amizade e isso torna o animal mais d\u00f3cil e condicionado \u00e0s montarias sem traumas&#8221;.<\/p>\n<p>\n\u00a0<\/p>\n<p>\nPara obter mais informa\u00e7\u00f5es sobre os cursos do setor de equinos e os locais onde ser\u00e3o realizados neste m\u00eas de setembro acesse o site <a href=\"http:\/\/www.senarmt.org.br\">www.senarmt.org.br<\/a> ou procure o Sindicato Rural de seu munic\u00edpio.<\/p>\n<p>\n\u00a0<\/p>\n<p>\n\u00a0<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso,\u00a0 atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT).<\/p>\n<p>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto sela o cavalo com cuidado e paci\u00eancia, o vaqueiro Erasmo Aparecido Pereira Leite, de 44 anos fala sobre as transforma\u00e7\u00f5es que ocorreram em sua vida nos \u00faltimos tempos. Segundo ele, depois que fez os cursos gratuitos oferecidos pelo Sindicado Rural de Ros\u00e1rio Oeste em parceria com Servi\u00e7o Nacional de Aprendizagem Rural (Senar-MT) sua renda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/09\/16092013095850-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 16 de setembro de 2013","modified":"Atualizado em 16 de setembro de 2013"},"absolute_dates_time":{"created":"Publicado em 16 de setembro de 2013 09:59","modified":"Atualizado em 16 de setembro de 2013 09:59"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11324"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5136"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}