{"id":11297,"date":"2013-08-14T11:10:10","date_gmt":"2013-08-14T14:10:10","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/08\/14\/academia-de-lideranca-acontece-neste-fim-de-semana-em-cuiaba\/"},"modified":"2013-08-14T11:10:10","modified_gmt":"2013-08-14T14:10:10","slug":"academia-de-lideranca-acontece-neste-fim-de-semana-em-cuiaba","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/08\/14\/academia-de-lideranca-acontece-neste-fim-de-semana-em-cuiaba\/","title":{"rendered":"Academia de Lideran\u00e7a acontece neste fim de semana em Cuiab\u00e1"},"content":{"rendered":"<p>\nNa pr&oacute;xima sexta-feira (16) e s&aacute;bado (17), os alunos da Academia de Lideran&ccedil;a, projeto desenvolvido pelo Servi&ccedil;o Nacional de Apredizagem Rural (Senar-MT) se re&uacute;nem mais uma vez em Cuiab&aacute;. A turma 1 discutir&aacute; rela&ccedil;&otilde;es governamentais e para a turma 2, o assunto &eacute; marketing. &ldquo;Com esse programa vamos preparar os gestores que est&atilde;o surgindo e os l&iacute;deres que j&aacute; atuam no setor de agroneg&oacute;cio. &Eacute; desta forma que o Senar-MT contribui para a forma&ccedil;&atilde;o de futuros l&iacute;deres e gestores&rdquo;, ressalta o presidente do Conselho Administrativo do Senar-MT, Rui Prado.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nA Academia de Lideran&ccedil;as propicia aos participantes a oportunidade de aprimorar suas compet&ecirc;ncias em gest&atilde;o para atender as crescentes demandas e desafios no setor agropecu&aacute;rio. Entre os diversos objetivos do programa est&aacute; a forma&ccedil;&atilde;o de lideran&ccedil;as em t&eacute;cnicas de gest&atilde;o, negocia&ccedil;&atilde;o e comunica&ccedil;&atilde;o. Outra meta importante &eacute; aumentar as compet&ecirc;ncias relacionadas &agrave; lideran&ccedil;a dos produtores e trabalhadores rurais de Mato Grosso e possibilitar a reflex&atilde;o sobre o seu papel na transforma&ccedil;&atilde;o da sociedade.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nNo m&oacute;dulo do m&ecirc;s passado mais de 50 alunos participaram das aulas onde foram discutidos assuntos como governan&ccedil;a no terceiro setor, conduzido pelo professor Jairo Laser Procianoy e gest&atilde;o por resultados com Gilberto Porto. Para o produtor rural e membro do sindicato rural de Tangar&aacute; da Serra, Vanderlei Reck a Academia de Lideran&ccedil;as incentiva a discuss&atilde;o e gera novas ideias. &ldquo;O conhecimento amplia a vis&atilde;o das rela&ccedil;&otilde;es entre os lideres e liderados&rdquo;.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nO p&uacute;blico alvo inclui lideran&ccedil;as dos sistemas sindicais patronais e dos trabalhadores. O grupo tamb&eacute;m &eacute; composto por lideran&ccedil;as regionais rurais e pessoas com grande potencial para se tornarem l&iacute;deres.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso,&nbsp; atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n<p>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na pr&oacute;xima sexta-feira (16) e s&aacute;bado (17), os alunos da Academia de Lideran&ccedil;a, projeto desenvolvido pelo Servi&ccedil;o Nacional de Apredizagem Rural (Senar-MT) se re&uacute;nem mais uma vez em Cuiab&aacute;. A turma 1 discutir&aacute; rela&ccedil;&otilde;es governamentais e para a turma 2, o assunto &eacute; marketing. &ldquo;Com esse programa vamos preparar os gestores que est&atilde;o surgindo e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/08\/14082013110941-300x193.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 14 de agosto de 2013","modified":"Atualizado em 14 de agosto de 2013"},"absolute_dates_time":{"created":"Publicado em 14 de agosto de 2013 11:10","modified":"Atualizado em 14 de agosto de 2013 11:10"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11297"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5082"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}