{"id":11296,"date":"2013-08-12T14:55:46","date_gmt":"2013-08-12T17:55:46","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/08\/12\/equipe-atende-mais-seis-municipios-mato-grossenses-ate-o-fim-de-agosto\/"},"modified":"2013-08-12T14:55:46","modified_gmt":"2013-08-12T17:55:46","slug":"equipe-atende-mais-seis-municipios-mato-grossenses-ate-o-fim-de-agosto","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/08\/12\/equipe-atende-mais-seis-municipios-mato-grossenses-ate-o-fim-de-agosto\/","title":{"rendered":"Equipe atende mais seis munic\u00edpios mato-grossenses at\u00e9 o fim de agosto"},"content":{"rendered":"<p>\nPara esta semana a equipe do Mutir&atilde;o Rural da Cidadania realizado pelo Servi&ccedil;o Nacional de Aprendizagem Rural (Senar-MT),&nbsp; Sindicatos Rurais, Governo do Estado e v&aacute;rios outros parceiros estar&aacute; nos munic&iacute;pios de Carlinda e Nova Can&atilde;a do Norte. &nbsp;Os trabalhos da pr&oacute;xima semana come&ccedil;am logo no domingo (18), em Peixoto de Azevedo. Em seguida a equipe vai para Matup&aacute;,&nbsp; Guarant&atilde; do Norte e Col&iacute;der. Nos primeiros dias de agosto a equipe j&aacute; passou por Nova Bandeirantes, Apiac&aacute;s Parana&iacute;ta e Alta Floresta.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nEm julho a equipe multidiciplinar do Mutir&atilde;o Rural da Cidadania passou por mais de 10 munic&iacute;pios. Ao todo foram atendidas 20.228 pessoas e realizados 223.553 atendimentos. &nbsp;O programa oferece gratuitamente diversas a&ccedil;&otilde;es&nbsp; para as comunidades rurais, ind&iacute;genas, quilombolas e ribeirinhas de Mato Grosso.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\n&nbsp;A equipe do Mutir&atilde;o Rural faz carteira de trabalho, Cadastro de Pessoas F&iacute;sicas (CPF), emite&nbsp; documentos pessoais e certid&otilde;es. O grupo tamb&eacute;m emite segunda via destes documentos. O dia de Mutir&atilde;o Rural da Cidadania tamb&eacute;m &eacute; bastante movimentando por palestras sobre&nbsp; esclarecimentos das &nbsp;leis de tr&acirc;nsito, direito do consumidor e inclus&atilde;o social. A equipe tamb&eacute;m faz Boletins de Ocorr&ecirc;ncia e v&aacute;rias outras a&ccedil;&otilde;es como aulas de inclus&atilde;o social, atividades f&iacute;sicas, culturais e de lazer tamb&eacute;m s&atilde;o realizadas.<\/p>\n<p>\n<br \/>\n&nbsp;<br \/>\nA novidade do Mutir&atilde;o Rural da Cidadania, este ano,&nbsp; &eacute; a parceria com a Secretaria de Estado de Sa&uacute;de. &quot;Com isso&nbsp; tamb&eacute;m podemos oferecer&nbsp; exames m&eacute;dicos, como o teste de glicemia e aferi&ccedil;&atilde;o da press&atilde;o arterial&quot;, explica o&nbsp; supervisor do Senar, Jo&atilde;o Vargas.<\/p>\n<p>Com a meta de realizar 550 mil atendimentos e beneficiar 55 mil pessoas, o Mutir&atilde;o Rural da Cidadania, em 2013, passar&aacute; pelos munic&iacute;pios das nove regionais do Senar-MT.&nbsp; &quot;Atendemos a popula&ccedil;&atilde;o urbana, mas nossa prioridade &eacute; o homem do campo. Cerca de 80% do total de atendimento deve ocorrer em comunidades da zona rural, onde acreditamos que o acesso aos servi&ccedil;os &eacute; mais dif&iacute;cil&quot;. Em 2012 foram beneficiadas 38.201 pessoas. O Mutir&atilde;o esteve em 99 munic&iacute;pios e fez 414.538 atendimentos.<\/p>\n<p>O programa tamb&eacute;m conta com a parceria da Secretaria de Seguran&ccedil;a P&uacute;blica, por meio da Pol&iacute;cia T&eacute;cnica (Politec), Rede Cidad&atilde;, Pol&iacute;cia Militar, Pol&iacute;cia Judici&aacute;ria Civil, o Sistema Nacional de Empregos (Sine), Procon, Detran, e vice-governadoria, atrav&eacute;s da Superintend&ecirc;ncia de Assuntos Ind&iacute;genas.<\/p>\n<p>\n&nbsp;<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso,&nbsp; atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n<p>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para esta semana a equipe do Mutir&atilde;o Rural da Cidadania realizado pelo Servi&ccedil;o Nacional de Aprendizagem Rural (Senar-MT),&nbsp; Sindicatos Rurais, Governo do Estado e v&aacute;rios outros parceiros estar&aacute; nos munic&iacute;pios de Carlinda e Nova Can&atilde;a do Norte. &nbsp;Os trabalhos da pr&oacute;xima semana come&ccedil;am logo no domingo (18), em Peixoto de Azevedo. Em seguida a equipe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":"https:\/\/sistemafamato.org.br\/senarmt\/wp-content\/uploads\/sites\/2\/2013\/08\/12082013025733-300x221.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 12 de agosto de 2013","modified":"Atualizado em 12 de agosto de 2013"},"absolute_dates_time":{"created":"Publicado em 12 de agosto de 2013 14:55","modified":"Atualizado em 12 de agosto de 2013 14:55"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11296"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media\/5080"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}