{"id":11264,"date":"2013-04-09T09:35:18","date_gmt":"2013-04-09T12:35:18","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/04\/09\/equoterapia-desenvolvida-pelo-senar-mt-recebe-mocao-de-aplausos\/"},"modified":"2013-04-09T09:35:18","modified_gmt":"2013-04-09T12:35:18","slug":"equoterapia-desenvolvida-pelo-senar-mt-recebe-mocao-de-aplausos","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2013\/04\/09\/equoterapia-desenvolvida-pelo-senar-mt-recebe-mocao-de-aplausos\/","title":{"rendered":"Equoterapia desenvolvida pelo Senar-MT recebe mo\u00e7\u00e3o de aplausos"},"content":{"rendered":"<p>\nO Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) recebeu Mo\u00e7\u00e3o de Aplausos da C\u00e2mara Municipal de Vereadores de Santo Antonio de Leveger pelo desenvolvimento do projeto de Equoterapia no munic\u00edpio. A honraria, em nome do presidente do Conselho Administrativo da entidade, Rui Prado, foi proposta pelo vereador Lu\u00eds Felipe Pedroso e aprovada pelos demais legisladores.<\/p>\n<p>\nO presidente da Casa de Leis de Santo Antonio do Leveger, vereador Wagner Belmiro Teixeira Silva, encaminhou of\u00edcio ao Senar-MT para informar a aprova\u00e7\u00e3o da Mo\u00e7\u00e3o e o diretor financeiro do Sindicato de Santo Antonio, Edson Andrade, trouxe o documento ao Senar-MT.<\/p>\n<p>\nA Equoterapia \u00e9 um projeto do Senar-MT, desenvolvido em parceria com o Sindicato Rurais de Cuiab\u00e1, Lucas do Rio Verde,\u00a0 Tangar\u00e1 da Serra,\u00a0 Sorriso, Sinop e Santo Antonio do Leverger. Cada um dos parceiros tem a meta de atender, no m\u00ednimo, 15 praticantes por m\u00eas. Em 2012, por meio das parcerias foram oferecidos 4800 atendimentos de Equoterapia. \u00a0<\/p>\n<p>\nO Senar-MT \u00e9 a \u00fanica Regional do Brasil que oferece o projeto de Equoterapia como uma das atividades do Programa Especial Apoena, que na l\u00edngua tupi-guarani quer dizer &#8220;aquele que enxerga longe&#8221;. O programa tem por objetivo a qualifica\u00e7\u00e3o de pessoas com necessidades especiais, estimulando a participa\u00e7\u00e3o de deficientes nos cursos ofertados pela institui\u00e7\u00e3o. \u00a0\u00a0\u00a0<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso,\u00a0 atuando em parceria com os 87 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT).<\/p>\n<p>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) recebeu Mo\u00e7\u00e3o de Aplausos da C\u00e2mara Municipal de Vereadores de Santo Antonio de Leveger pelo desenvolvimento do projeto de Equoterapia no munic\u00edpio. A honraria, em nome do presidente do Conselho Administrativo da entidade, Rui Prado, foi proposta pelo vereador Lu\u00eds Felipe Pedroso e aprovada pelos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11264","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 9 de abril de 2013","modified":"Atualizado em 9 de abril de 2013"},"absolute_dates_time":{"created":"Publicado em 9 de abril de 2013 09:35","modified":"Atualizado em 9 de abril de 2013 09:35"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11264"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11264\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}