{"id":11206,"date":"2012-12-07T11:51:08","date_gmt":"2012-12-07T13:51:08","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/12\/07\/augusto-cury-debate-futuro-da-educacao-em-mato-grosso\/"},"modified":"2012-12-07T11:51:08","modified_gmt":"2012-12-07T13:51:08","slug":"augusto-cury-debate-futuro-da-educacao-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/12\/07\/augusto-cury-debate-futuro-da-educacao-em-mato-grosso\/","title":{"rendered":"Augusto Cury debate Futuro da Educa\u00e7\u00e3o em Mato Grosso"},"content":{"rendered":"<p>\nO Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) traz o escritor Augusto Cury para debater com os instrutores da institui&ccedil;&atilde;o o &quot;Futuro da Educa&ccedil;&atilde;o&quot;. O evento ser&aacute; no dia 13 de dezembro, durante a 1&ordf; Parceria Educacional promovida pela entidade de ensino rural. Al&eacute;m do <em>Talk Show<\/em> com Augusto Cury, a Parceria Educacional ir&aacute; promover a din&acirc;mica de<em> Word Caf&eacute;<\/em> com a psic&oacute;loga Adriana Meirelles e a palestra &quot;A m&aacute;gica da motiva&ccedil;&atilde;o para educadores&quot;, com Eduardo Peres.<\/p>\n<p>\n&quot;O Senar-MT atende cerca de 45 mil pessoas em treinamentos a cada ano, atuamos nos 141 munic&iacute;pios do Estado, seja por meio de parcerias com os Sindicatos Rurais ou com as prefeituras, e quem ajuda o Senar a levar todo esse conhecimento e mudan&ccedil;a de vida ao homem do campo s&atilde;o os nossos instrutores, nada mais justo do que comemorarmos esses resultados com eles e tamb&eacute;m planejarmos o futuro da educa&ccedil;&atilde;o profissional rural juntos&quot;, revelou o presidente do Conselho Administrativo do Senar-MT, Rui Prado.<\/p>\n<p>\nO encontro ter&aacute; in&iacute;cio &agrave;s 7h30 no <em>Cenarium Rural<\/em>, com o credenciamento dos instrutores. As boas vindas ser&atilde;o feitas pelo presidente do conselho do Senar seguida pela apresenta&ccedil;&atilde;o &quot;Os novos horizontes do Senar-MT&quot;, que ser&aacute; feita pelo superintendente da institui&ccedil;&atilde;o, Tiago Mattosinho.&nbsp; &quot;Preparamos um dia especial para os instrutores do Senar-MT, respons&aacute;veis por levar a miss&atilde;o da institui&ccedil;&atilde;o a campo&quot;, revelou o superintendente.<\/p>\n<p>\n<strong>Palestrantes <\/strong><\/p>\n<p>\nAugusto Cury &ndash; Al&eacute;m de escritor &eacute; m&eacute;dico psiquiatra, psicoterapeuta e cientista, p&oacute;s-graduado no Centre Medical Marmottan- Paris- Fran&ccedil;a. Segundo o jornal Folha de S&atilde;o Paulo, &eacute; o autor mais lido da d&eacute;cada, j&aacute; vendeu mais de 16 milh&otilde;es de livros no Brasil e se tornou <em>best seller<\/em> em v&aacute;rios pa&iacute;ses. V&aacute;rias faculdades e universidades adotam suas obras. Cury produziu uma nova teoria sobre a l&oacute;gica do pensamento, o processo de interpreta&ccedil;&atilde;o e o processo de forma&ccedil;&atilde;o de pensadores.Entre suas obras est&atilde;o:&nbsp; &quot;Seja l&iacute;der de si mesmo&quot;, &quot;O C&oacute;digo da Intelig&ecirc;ncia&quot;, e &quot;Mentes Brilhantes, Mentes Treinadas&quot;.<\/p>\n<p>\nAdriana Meirelles &ndash; Psic&oacute;loga, MBA em Desenvolvimento e Gerenciamento de Talentos, vencedora do Pr&ecirc;mio ABRH (Associa&ccedil;&atilde;o Brasileira de Recursos Humanos) com as melhores Pr&aacute;ticas em Gest&atilde;o de Pessoas e com 10 anos de experi&ecirc;ncia na &aacute;rea de Gest&atilde;o de pessoas atrav&eacute;s de gerenciamento humano<\/p>\n<p>\nEduardo Peres &ndash; Autor do livro &quot;Pensamento Original em Arte M&aacute;gica&quot; . &Eacute; palestrante refer&ecirc;ncia em aberturas e encerramentos de f&oacute;runs empresariais, treinamentos <em>in company <\/em>e semin&aacute;rios acad&ecirc;micos, corporativos e pol&iacute;ticos no Brasil e no exterior. Tem como clientes empresas como Petrobr&aacute;s, Correios (ECT SP, MG e RS), Casa da Moeda do Brasil, Caixa Econ&ocirc;mica Federal, Universidade de S&atilde;o Paulo, TRE-PI, Banco Ita&uacute; (Cr&eacute;dito Imobili&aacute;rio e Bank-Phone), Unimed, Pfizer, CCR-AutoBAn, Samsung, Banco Santander-Brasil, Adam&rsquo;s Cadbury, Bayer Cropscience, Visanet, Redecard, Sabesp, Basf, Duratex, entre outras.<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <strong>@senar_mt<\/strong> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\"><strong>http:\/\/www.facebook.com\/SenarMt<\/strong><\/a>) da institui&ccedil;&atilde;o de ensino rural, que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) traz o escritor Augusto Cury para debater com os instrutores da institui&ccedil;&atilde;o o &quot;Futuro da Educa&ccedil;&atilde;o&quot;. O evento ser&aacute; no dia 13 de dezembro, durante a 1&ordf; Parceria Educacional promovida pela entidade de ensino rural. Al&eacute;m do Talk Show com Augusto Cury, a Parceria Educacional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11206","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 13 anos atr\u00e1s","modified":"Atualizado 13 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 7 de dezembro de 2012","modified":"Atualizado em 7 de dezembro de 2012"},"absolute_dates_time":{"created":"Publicado em 7 de dezembro de 2012 11:51","modified":"Atualizado em 7 de dezembro de 2012 11:51"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11206"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11206\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}