{"id":11192,"date":"2012-11-05T10:19:33","date_gmt":"2012-11-05T12:19:33","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/11\/05\/prorrogado-prazo-de-inscricoes-para-processo-seletivo\/"},"modified":"2012-11-05T10:19:33","modified_gmt":"2012-11-05T12:19:33","slug":"prorrogado-prazo-de-inscricoes-para-processo-seletivo","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/11\/05\/prorrogado-prazo-de-inscricoes-para-processo-seletivo\/","title":{"rendered":"Prorrogado prazo de inscri\u00e7\u00f5es para processo seletivo"},"content":{"rendered":"<p>\nO Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) prorrogou o prazo de inscri&ccedil;&otilde;es para o processo seletivo da institui&ccedil;&atilde;o at&eacute; as 18h00 do dia 12 de novembro. Para participar, os interessados devem acessar o banner &quot;oportunidade &uacute;nica&quot; na p&aacute;gina principal do site do Sistema Famato ou do Grupo Valure (<a href=\"http:\/\/www.grupovalure.com.br\">www.grupovalure.com.br<\/a>) e fazer o cadastro. As inscri&ccedil;&otilde;es s&atilde;o gratuitas e ser&atilde;o aceitas somente pela internet.<\/p>\n<p>\nA contrata&ccedil;&atilde;o dos selecionados se dar&aacute; pelo regime da Consolida&ccedil;&atilde;o das Leis do Trabalho (CLT). As vagas dispon&iacute;veis s&atilde;o para os cargos: zelador (1 vaga), tesoureiro (1 vaga), auxiliar administrativo (1 vaga), auxiliar administrativo de educa&ccedil;&atilde;o profissional em Cuiab&aacute; (1 vaga), assistente de aprendizagem rural (1 vaga), assistente cont&aacute;bil (1 vaga), assistente administrativo (1 vaga),&nbsp; &nbsp;assistente administrativo de aquisi&ccedil;&atilde;o e suprimentos (2 vagas), designer gr&aacute;fico (1 vaga), analista em comunica&ccedil;&atilde;o, marketing e eventos (1 vaga), analista jur&iacute;dico (1 vaga), analista de educa&ccedil;&atilde;o profissional &ndash; veterin&aacute;rio (1 vaga), analista de educa&ccedil;&atilde;o profissional &ndash; zootecnista (1 vaga), analista de educa&ccedil;&atilde;o profissional &ndash; agr&ocirc;nomo (1 vaga) e&nbsp; auxiliar administrativo de educa&ccedil;&atilde;o profissional em Campo Novo do Parecis (1 vaga).<\/p>\n<p>\nO processo de sele&ccedil;&atilde;o ser&aacute; realizado em tr&ecirc;s etapas. A primeira etapa &eacute; de analise curricular, a segunda constitui-se de uma din&acirc;mica de grupo seguida por uma prova de reda&ccedil;&atilde;o. A terceira e ultima etapa ser&aacute; a entrevista e an&aacute;lise psicol&oacute;gica. As datas das duas &uacute;ltimas etapas ser&atilde;o informadas oportunamente pela empresa respons&aacute;vel pelo processo.<\/p>\n<p>\nO superintendente do Senar-MT explica que as novas contrata&ccedil;&otilde;es fazem parte do Plano de Expans&atilde;o da institui&ccedil;&atilde;o que acompanha a evolu&ccedil;&atilde;o do setor agropecu&aacute;rio de Mato Grosso. &quot;Nos &uacute;ltimos 10 anos tivemos um enorme crescimento no setor rural do Estado e o Senar cresceu junto, tanto em rela&ccedil;&atilde;o a sua estrutura quanto em rela&ccedil;&atilde;o &agrave; arrecada&ccedil;&atilde;o&quot;, explica. &quot;Esse crescimento exigiu um plano de expans&atilde;o, para que possamos atender as novas demandas por treinamentos e cursos de capacita&ccedil;&atilde;o&quot;, completa. O processo seletivo est&aacute; sendo divulgado tamb&eacute;m em jornais, r&aacute;dios, e nas principais faculdades de Cuiab&aacute;.<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#!\/senar_mt\"><strong>@senar_mt<\/strong><\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" title=\"Link de acesso\" rel=\"noopener\"><strong>http:\/\/www.facebook.com\/SenarMt<\/strong><\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) prorrogou o prazo de inscri&ccedil;&otilde;es para o processo seletivo da institui&ccedil;&atilde;o at&eacute; as 18h00 do dia 12 de novembro. Para participar, os interessados devem acessar o banner &quot;oportunidade &uacute;nica&quot; na p&aacute;gina principal do site do Sistema Famato ou do Grupo Valure (www.grupovalure.com.br) e fazer o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11192","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 5 de novembro de 2012","modified":"Atualizado em 5 de novembro de 2012"},"absolute_dates_time":{"created":"Publicado em 5 de novembro de 2012 10:19","modified":"Atualizado em 5 de novembro de 2012 10:19"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11192"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11192\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}