{"id":11188,"date":"2012-10-25T17:52:29","date_gmt":"2012-10-25T19:52:29","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/10\/25\/expedicao-ira-percorrer-13-municipios-em-mato-grosso\/"},"modified":"2012-10-25T17:52:29","modified_gmt":"2012-10-25T19:52:29","slug":"expedicao-ira-percorrer-13-municipios-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/10\/25\/expedicao-ira-percorrer-13-municipios-em-mato-grosso\/","title":{"rendered":"Expedi\u00e7\u00e3o ir\u00e1 percorrer 13 munic\u00edpios em Mato Grosso"},"content":{"rendered":"<p>\nDois &#8216;mini dias&#8217; de campo, uma oficina de Mecaniza\u00e7\u00e3o Agr\u00edcola, outra de Sa\u00fade e Seguran\u00e7a do Trabalhador (NR 31.8), al\u00e9m de ouvir muitas experi\u00eancias sobre a produ\u00e7\u00e3o de soja no Estado s\u00e3o a\u00e7\u00f5es planejadas pelos representantes do Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) durante a rota Mato Grosso da Expedi\u00e7\u00e3o Soja Brasil, projeto patrocinado pela entidade e realizado pela Associa\u00e7\u00e3o Brasileira dos Produtores de Soja (Aprosoja Brasil) em parceria com Empresa Brasileira de Pesquisa Agropecu\u00e1ria (Embrapa) e o Canal Rural.\u00a0<\/p>\n<p>\nAt\u00e9 mar\u00e7o de 2013, o Projeto Soja Brasil ir\u00e1 percorrer 11 estados brasileiros (somando 25 mil quil\u00f4metros) para conferir o desenvolvimento das lavouras do plantio at\u00e9 a colheita do gr\u00e3o. Para a realiza\u00e7\u00e3o do projeto foram definidas quatro rotas e tudo ser\u00e1 transmitido pelo Canal Rural nos programas Bom Dia Campo, Mercado &#038; Cia e Rural Not\u00edcias.<\/p>\n<p>\nA equipe do Senar-MT, formada pelo supervisor Rafael Fabri, pela jornalista Alcione dos Anjos e pelos instrutores Carlos Danielli (\u00c1rea de Mecaniza\u00e7\u00e3o Agr\u00edcola) e Val\u00e9ria Eller (\u00c1rea de Seguran\u00e7a do Trabalho), participar\u00e1 durante 17 dias da rota que pertence a Mato Grosso, visitando propriedades produtoras do gr\u00e3o. &#8220;O Senar participa da expedi\u00e7\u00e3o mostrando o que a institui\u00e7\u00e3o faz, que \u00e9 capacitar o produtor e trabalhador rural, para que ele saiba gerenciar a sua lavoura da melhor forma poss\u00edvel&#8221;, explica o superintendente do Senar-MT, Tiago Mattosinho. &#8220;Esse projeto ser\u00e1 muito importante para mostrarmos a sociedade que o Senar-MT est\u00e1 preparado para atender o produtor e trabalhador com capacita\u00e7\u00f5es que contemple toda a cadeia da Soja&#8221;, avaliou.<\/p>\n<p>\nA aventura por lavouras em Mato Grosso come\u00e7ar\u00e1 segunda-feira (29.10) por Campos de J\u00falio (600 km de Cuiab\u00e1), passar\u00e1 por Sapezal, Campo Novo do Parecis, Diamantino, Sorriso, Ipiranga do Norte, Sinop, Sorriso, Lucas do Rio Verde, Nova Mutum, Campo Verde, Primavera do Leste, Rondon\u00f3polis e por fim chegar\u00e1 a Alto Taquari, no dia 16 de novembro. O Projeto Soja Brasil \u00e9 uma realiza\u00e7\u00e3o da Aprosoja Brasil, do Senar-MT e do Canal Rural, com coordena\u00e7\u00e3o t\u00e9cnica da Embrapa e patroc\u00ednio de BASF, Mitsubishi Motors e Monsanto.<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga <a href=\"mailto:@senar_mt\"><strong>@senar_mt<\/strong><\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" title=\"Link de acesso\" rel=\"noopener\"><strong>http:\/\/www.facebook.com\/SenarMt<\/strong><\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois &#8216;mini dias&#8217; de campo, uma oficina de Mecaniza\u00e7\u00e3o Agr\u00edcola, outra de Sa\u00fade e Seguran\u00e7a do Trabalhador (NR 31.8), al\u00e9m de ouvir muitas experi\u00eancias sobre a produ\u00e7\u00e3o de soja no Estado s\u00e3o a\u00e7\u00f5es planejadas pelos representantes do Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) durante a rota Mato Grosso da Expedi\u00e7\u00e3o Soja Brasil, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11188","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 25 de outubro de 2012","modified":"Atualizado em 25 de outubro de 2012"},"absolute_dates_time":{"created":"Publicado em 25 de outubro de 2012 17:52","modified":"Atualizado em 25 de outubro de 2012 17:52"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11188"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11188\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}