{"id":11174,"date":"2012-09-28T18:08:11","date_gmt":"2012-09-28T21:08:11","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/09\/28\/senar-mt-e-a-instituicao-mais-lembrada-na-categoria-educacao\/"},"modified":"2012-09-28T18:08:11","modified_gmt":"2012-09-28T21:08:11","slug":"senar-mt-e-a-instituicao-mais-lembrada-na-categoria-educacao","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/09\/28\/senar-mt-e-a-instituicao-mais-lembrada-na-categoria-educacao\/","title":{"rendered":"Senar-MT \u00e9 a institui\u00e7\u00e3o mais lembrada na categoria Educa\u00e7\u00e3o"},"content":{"rendered":"<p>\nPelo segundo ano consecutivo o Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) foi homenageado com o Pr&ecirc;mio Top Of Mind 2012. O Senar-MT foi a marca mais lembrada no segmento Educa&ccedil;&atilde;o, categoria Ensino de Aprendizagem Rural. A premia&ccedil;&atilde;o ocorreu na noite de quinta-feira (27.09) e a institui&ccedil;&atilde;o rural foi representada pelo conselheiro da institui&ccedil;&atilde;o, Jos&eacute; Jorge Sobrinho. O conselheiro estava acompanhado da esposa, Elenice Ferreira.<\/p>\n<p>\nEsta &eacute; a 7&ordf; edi&ccedil;&atilde;o pr&ecirc;mio, idealizado pela Revista RDM (Revista de Mato Grosso), em parceria com a Revista BSB Brasil, e com pesquisa de mercado feita pela NewComDates, em diversas cidades. Al&eacute;m do Senar foram premiadas empresas em dezenas de categorias nos setores industrial, comercial e prestadores de servi&ccedil;os. A solenidade foi no Buffet Leila Maluf.<\/p>\n<p>\nO conselheiro da institui&ccedil;&atilde;o agradeceu as centenas de pessoas que escolheram o Senar-MT como refer&ecirc;ncia de ensino rural e elogiou a iniciativa da revista RDM.&nbsp; &quot;&Eacute; um reconhecimento ao trabalho que o Senar desenvolve h&aacute; quase 20 anos em Mato Grosso&quot;, avaliou. &quot;A premia&ccedil;&atilde;o foi muito boa e extremamente significativa, pois reconhece que o Senar-MT &eacute; uma entidade que est&aacute; fazendo de maneira correta seu papel, ou seja, qualificando e capacitando trabalhadores e produtores rurais com objetivo de gerar de emprego e renda, enfim, promovendo o desenvolvimento do nosso Estado&quot;, argumentou.<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pelo segundo ano consecutivo o Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) foi homenageado com o Pr&ecirc;mio Top Of Mind 2012. O Senar-MT foi a marca mais lembrada no segmento Educa&ccedil;&atilde;o, categoria Ensino de Aprendizagem Rural. A premia&ccedil;&atilde;o ocorreu na noite de quinta-feira (27.09) e a institui&ccedil;&atilde;o rural foi representada pelo conselheiro da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11174","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 28 de setembro de 2012","modified":"Atualizado em 28 de setembro de 2012"},"absolute_dates_time":{"created":"Publicado em 28 de setembro de 2012 18:08","modified":"Atualizado em 28 de setembro de 2012 18:08"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11174"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11174\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}