{"id":11167,"date":"2012-09-14T19:10:59","date_gmt":"2012-09-14T22:10:59","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/09\/14\/produtores-e-trabalhadores-rurais-discutem-sistema-juridico\/"},"modified":"2012-09-14T19:10:59","modified_gmt":"2012-09-14T22:10:59","slug":"produtores-e-trabalhadores-rurais-discutem-sistema-juridico","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/09\/14\/produtores-e-trabalhadores-rurais-discutem-sistema-juridico\/","title":{"rendered":"Produtores e trabalhadores rurais discutem sistema jur\u00eddico"},"content":{"rendered":"<p>\nAs quest\u00f5es trabalhista, ind\u00edgenas e de distribui\u00e7\u00e3o dos Royalties do Petr\u00f3leo ser\u00e3o os tr\u00eas grandes temas que dominar\u00e3o as discuss\u00f5es do Congresso Nacional em rela\u00e7\u00e3o ao setor rural em 2013. A previs\u00e3o foi feita pelo senador Pedro Taques, que ministrou uma palestra sobre o Sistema Jur\u00eddico Brasileiro durante o Programa Academia de Lideran\u00e7a na manh\u00e3 dessa sexta-feira (14 de setembro). &#8220;Apenas por meio do di\u00e1logo iremos construir consensos e resolver todas as quest\u00f5es que envolvem a sociedade democratica&#8221;, disse Taques.<\/p>\n<p>\nO programa foi idealizado pela Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria de Mato Grosso (Famato) e realizado pelo Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) em parceria com a Funda\u00e7\u00e3o Dom Cabral (FDC), de Minas Gerais. Ele re\u00fane representantes de diversos segmentos da \u00e1rea rural: Federa\u00e7\u00e3o dos Trabalhadores na Agricultura do Estado de Mato Grosso (Fetagri-MT), sindicatos rurais, associa\u00e7\u00f5es de produtores rurais, e ainda colaboradores do Sistema Famato\/ Senar\u00a0 e do Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea). &#8220;O objetivo do programa \u00e9 qualificar l\u00edderes capazes de multiplicar conhecimentos e de mobilizar a classe produtora em beneficio do desenvolvimento do setor&#8221;, explicou o superintendente do Senar-MT, Tiago Mattosinho.<\/p>\n<p>\nO gerente de Aprendizagem Rural do Senar, Marciel Becker, lembra que s\u00e3o quatro meses de programa, per\u00edodo em que 120 lideran\u00e7as ser\u00e3o habilitadas a exercer o seu papel da melhor forma poss\u00edvel e isso passa pelo entendimento do que \u00e9 o Sistema Jur\u00eddico Brasileiro. &#8220;O importante desse m\u00f3dulo \u00e9 que essas lideran\u00e7as entendam a din\u00e2mica do Sistema Jur\u00eddico, a harmonia dos poderes e que saibam se posicionar perante os temas que est\u00e3o imposto, e ainda saber o que precisa ser feito para melhorar esse processo&#8221;.\u00a0<\/p>\n<p>\nSegundo o palestrante capacita\u00e7\u00f5es como esta contribuem para o desenvolvimento de toda a sociedade. \u201cO debate faz com que superemos preconceitos e avancemos em uma sociedade mais democr\u00e1tica. Nesse sentido a discuss\u00e3o sobre o Sistema Jur\u00eddico Brasileiro \u00e9 fundamental, pois diz respeito \u00e0 cidadania e \u00e0 democracia\u201d.<\/p>\n<p>\nPara o presidente do sindicato de Campo Novo dos Parecis, Alex Utida, o produtor de Mato Grosso est\u00e1 deixando de ser um colono para se transformar em um empres\u00e1rio do agroneg\u00f3cio e precisa de treinamentos que desenvolva novas habilidades e compet\u00eancias. &#8220;Sou da terceira gera\u00e7\u00e3o de uma fam\u00edlia de produtores e posso dizer que estamos vivendo um momento importante onde as lideran\u00e7as precisam pensar nossa regi\u00e3o, nosso estado e nosso pa\u00eds e o programa colabora com esse objetivo&#8221;, afirma.<\/p>\n<p>\nO representante do Sindicato dos Trabalhadores de Pontes e Lacerda, Jos\u00e9 Aparecido da Silva, o Cid\u00e3o, revela que trabalha desde menino na ro\u00e7a com o pai e tem orgulho disso. Para ele a uni\u00e3o de for\u00e7as \u00e9 o que garante o desenvolvimento do setor. &#8220;Antes cada um ficava no seu peda\u00e7o de terra e ficava por isso mesmo, hoje estamos juntos com grandes produtores com a agricultura familiar na busca de conhecimento para melhorar a agricultura&#8221;, revela. &#8220;Sempre que tem um curso do Senar eu participo, porque sei que isso faz a diferen\u00e7a na minha vida&#8221;, declara.<\/p>\n<p>\nO Senar est\u00e1 no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui\u00e7\u00e3o de ensino rural que est\u00e1 presente em todos os munic\u00edpios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As quest\u00f5es trabalhista, ind\u00edgenas e de distribui\u00e7\u00e3o dos Royalties do Petr\u00f3leo ser\u00e3o os tr\u00eas grandes temas que dominar\u00e3o as discuss\u00f5es do Congresso Nacional em rela\u00e7\u00e3o ao setor rural em 2013. A previs\u00e3o foi feita pelo senador Pedro Taques, que ministrou uma palestra sobre o Sistema Jur\u00eddico Brasileiro durante o Programa Academia de Lideran\u00e7a na manh\u00e3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11167","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 14 de setembro de 2012","modified":"Atualizado em 14 de setembro de 2012"},"absolute_dates_time":{"created":"Publicado em 14 de setembro de 2012 19:10","modified":"Atualizado em 14 de setembro de 2012 19:10"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11167"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11167\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}