{"id":11149,"date":"2012-08-16T15:52:20","date_gmt":"2012-08-16T18:52:20","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/08\/16\/senar-e-sindicatos-rurais-definem-treinamentos-para-2013\/"},"modified":"2012-08-16T15:52:20","modified_gmt":"2012-08-16T18:52:20","slug":"senar-e-sindicatos-rurais-definem-treinamentos-para-2013","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/08\/16\/senar-e-sindicatos-rurais-definem-treinamentos-para-2013\/","title":{"rendered":"Senar e Sindicatos Rurais definem treinamentos para 2013"},"content":{"rendered":"<p>\nTeve in&iacute;cio nessa semana as reuni&otilde;es do Plano Anual de Trabalho (PAT) realizadas Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), por meio das suas nove regionais, em conjunto com &nbsp;os sindicatos rurais dos munic&iacute;pios. De acordo com o gerente de Aprendizagem Rural da institui&ccedil;&atilde;o rural, Marciel Becker, os resultados desses encontros servir&atilde;o para planejar os cursos e treinamentos ofertados em cada munic&iacute;pio em 2013. &quot;As reuni&otilde;es ocorrem at&eacute; o dia 24 de agosto, nessa fase estamos ouvindo as demandas da sociedade rural, ou seja, quais cursos da grade do Senar eles t&ecirc;m interesse em realizar no pr&oacute;ximo ano&quot;, explica.<\/p>\n<p>\nBecker destaca que o Senar possui mais de 100 diferentes tipos de treinamentos e cursos de Forma&ccedil;&atilde;o Profissional Rural (FPR) e Promo&ccedil;&atilde;o Social (PS) nas &aacute;reas de agricultura, pecu&aacute;ria, silvicultura, aquicultura, extrativismo, presta&ccedil;&atilde;o de servi&ccedil;os, agroind&uacute;stria, atividade de apoio agrossilvipastoril, artesanato, educa&ccedil;&atilde;o, alimenta&ccedil;&atilde;o e nutri&ccedil;&atilde;o. Al&eacute;m disso, oferece programas especiais focados na gest&atilde;o de propriedades, seguran&ccedil;a do trabalho, empreendedorismo, atendimento &agrave;s pessoas com defici&ecirc;ncia, cidadania e inclus&atilde;o digital rural. &quot;Al&eacute;m dos nove programas j&aacute; ofertados, em 2012 lan&ccedil;amos os programas Filhos no Campo e Sucess&atilde;o Familiar&quot;, cita.<\/p>\n<p>\nO PAT ocorre todos os anos no m&ecirc;s de agosto, ap&oacute;s a consolida&ccedil;&atilde;o da demanda os pedidos s&atilde;o apresentadas ao Senar-Central para aprova&ccedil;&atilde;o or&ccedil;ament&aacute;ria, s&oacute; depois dessa fase os cursos entram na programa&ccedil;&atilde;o do Senar de Mato Grosso. Nessa quinta-feira (16.08), por exemplo, uma das reuni&otilde;es do PAT foi realizada no Sindicato Rural de Campin&aacute;polis, com a presen&ccedil;a do presidente, Joaquim Jos&eacute; de Almeida, da mobilizadora Analice Nunes e parceiros (representantes da cooperativa de produtores de leite, da Comunidade Rural S&atilde;o Jos&eacute; do Couto, do Clube da Melhor idade, dos Assentamentos Santa C&eacute;lia e Santa Cruz).<\/p>\n<p>\n&quot;Foram demandados 36 treinamentos, um aumento de aproximadamente 20%, visto que o sindicato j&aacute; realizou 20 treinamentos e ainda h&aacute; mais 10 programados para 2012&quot;, relatou o supervisor da regional de Barra do Gar&ccedil;as, Rafael Fabri. Para Analice o PAT &eacute; importante para que o sindicato possa levantar a real demanda de cada parceiro, atendendo-os da melhor forma poss&iacute;vel. O presidente do sindicato avalia de forma positiva a a&ccedil;&atilde;o do Senar na regi&atilde;o. &quot;Os treinamentos realizados em parceria com o Senar s&atilde;o de grande valia para comunidade, visto que, nosso munic&iacute;pio &eacute; carente de m&atilde;o de obra qualificada. Essa capacita&ccedil;&atilde;o &eacute; importante para nossa realidade que tem na pecu&aacute;ria de leite a base da economia&quot;, apontou.<\/p>\n<p>\nJ&aacute; o munic&iacute;pio de C&aacute;ceres ira realizar a reuni&atilde;o do PAT sexta-feira (17.08) como informa o supervisor do Senar da regional de S&atilde;o Jos&eacute; dos Quatro Marcos, Paulo Henrique Mour&atilde;o. &quot;O Sindicato Rural cuidou convidou representantes de entidades e institui&ccedil;&otilde;es como Sindicato dos Trabalhadores Rurais, Associa&ccedil;&otilde;es de Produtores Rurais, C&acirc;mara Municipal, Secretaria Municipal de Agricultura, Unemat, Indea, Empaer, IFMT, Uni&atilde;o de Associa&ccedil;&otilde;es Rurais e Comunit&aacute;rias de C&aacute;ceres, Pastoral da Crian&ccedil;a e associados ao Sindicato Rural&quot;, citou.<\/p>\n<p>\nO presidente em exerc&iacute;cio do Sindicato Rural de C&aacute;ceres, Jeremias Pereira Leite, ressalta a import&acirc;ncia de cada participante trazer o esbo&ccedil;o da demanda a ser apresentada para a agilidade dos trabalhos. &quot;Esperamos a participa&ccedil;&atilde;o de todos devido a import&acirc;ncia da reuni&atilde;o, pois o Senar quer oferecer os cursos de acordo com a necessidade e vontade do p&uacute;blico alvo&quot;, comentou.<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teve in&iacute;cio nessa semana as reuni&otilde;es do Plano Anual de Trabalho (PAT) realizadas Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), por meio das suas nove regionais, em conjunto com &nbsp;os sindicatos rurais dos munic&iacute;pios. De acordo com o gerente de Aprendizagem Rural da institui&ccedil;&atilde;o rural, Marciel Becker, os resultados desses encontros servir&atilde;o para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11149","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 16 de agosto de 2012","modified":"Atualizado em 16 de agosto de 2012"},"absolute_dates_time":{"created":"Publicado em 16 de agosto de 2012 15:52","modified":"Atualizado em 16 de agosto de 2012 15:52"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11149"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11149\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}