{"id":11144,"date":"2012-08-08T11:27:34","date_gmt":"2012-08-08T14:27:34","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/08\/08\/senar-oferece-oficina-inedita-de-colhedora-de-cana-na-exposicao\/"},"modified":"2012-08-08T11:27:34","modified_gmt":"2012-08-08T14:27:34","slug":"senar-oferece-oficina-inedita-de-colhedora-de-cana-na-exposicao","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/08\/08\/senar-oferece-oficina-inedita-de-colhedora-de-cana-na-exposicao\/","title":{"rendered":"Senar oferece oficina in\u00e9dita de colhedora de cana na Exposi\u00e7\u00e3o"},"content":{"rendered":"<p>\nTer&aacute; in&iacute;cio quinta-feira (09.08) a 30&ordf; Exposi&ccedil;&atilde;o Agropecu&aacute;ria de Barra do Bugres (Expoagro 2012), que segue at&eacute; domingo (12.08), no Parque de Exposi&ccedil;&otilde;es Ren&ecirc; Barbour. &nbsp;Durante o evento, o Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), em parceira com o Sindicato Rural, ir&aacute; oferecer oito oficinas, sendo duas por noite, com intuito de divulgar as a&ccedil;&otilde;es realizadas pela institui&ccedil;&atilde;o de ensino no Estado. O presidente do Sindicato Rural de Barra do Bugres, Rog&eacute;rio Romanini convida a todos para participarem da feira agropecu&aacute;ria e visitarem o stand do Senar.<\/p>\n<p>\nA Expoagro de Barra do Bugres traz duas novidades. A apresenta&ccedil;&atilde;o dos resultados alcan&ccedil;ados com o Programa Jovem Aprendiz Rural, realiza&ccedil;&atilde;o do Senar em parceira com o sindicato e a Usina Barralcool e a oficina de Opera&ccedil;&atilde;o e Manuten&ccedil;&atilde;o de Colhedora de cana-de-a&ccedil;&uacute;car, in&eacute;dita em feiras agropecu&aacute;rias, por&eacute;m muito solicitada no munic&iacute;pio j&aacute; que a regi&atilde;o &eacute; produtora de cana.<\/p>\n<p>\n&quot;O programa Jovem Aprendiz Rural j&aacute; tem oito meses de dura&ccedil;&atilde;o e na exposi&ccedil;&atilde;o os aprendizes ir&atilde;o fazer um relato do que aprenderam nesse per&iacute;odo&quot;, conta a instrutora do programa Lilian Campos. &quot;L&aacute; haver&aacute; fotos, exposi&ccedil;&atilde;o do blog e uma horta suspensa criada pelos pr&oacute;prios aprendizes&quot;, revela a instrutora. O Programa Jovem Aprendiz Rural &eacute; voltado aos jovens de 14 a 24 anos de idade, teve in&iacute;cio em novembro de 2011 e se encerra em agosto deste ano. O objetivo &eacute; a forma&ccedil;&atilde;o profissional rural dos participantes.<\/p>\n<p>\nAl&eacute;m da oficina de Opera&ccedil;&atilde;o e Manuten&ccedil;&atilde;o e Colhedora de cana-de-a&ccedil;&uacute;car outras sete ser&atilde;o ofertadas nos dias de feira. Abaixo as oficinas e os dias da atividade:<\/p>\n<p>\n<strong>Dia 09\/08<\/strong><\/p>\n<p>\nOficina de pintura em tecido<br \/>\nOficina de confec&ccedil;&atilde;o de cabresto em couro bovino<\/p>\n<p>\n<strong>Dia 10\/08<\/strong><\/p>\n<p>\nOficina de confec&ccedil;&atilde;o de cintos em couro bovino<br \/>\nOficina manuten&ccedil;&atilde;o de tratores agr&iacute;colas<\/p>\n<p>\n<strong>Dia 11\/08<\/strong><\/p>\n<p>\nOficina fabrica&ccedil;&atilde;o de utens&iacute;lios de montaria<br \/>\nOficina opera&ccedil;&atilde;o e manuten&ccedil;&atilde;o de colhedora de cana-de-a&ccedil;&uacute;car<\/p>\n<p>\n<strong>Dia 12\/08<\/strong><\/p>\n<p>\nOficina de confec&ccedil;&atilde;o de revestimento para copos em couro bovino<br \/>\nOficina NR 31.8-seguran&ccedil;a do trabalhador na aplica&ccedil;&atilde;o de agrot&oacute;xicos<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso. O Senar atua em parceria com os 86 sindicatos rurais e faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ter&aacute; in&iacute;cio quinta-feira (09.08) a 30&ordf; Exposi&ccedil;&atilde;o Agropecu&aacute;ria de Barra do Bugres (Expoagro 2012), que segue at&eacute; domingo (12.08), no Parque de Exposi&ccedil;&otilde;es Ren&ecirc; Barbour. &nbsp;Durante o evento, o Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), em parceira com o Sindicato Rural, ir&aacute; oferecer oito oficinas, sendo duas por noite, com intuito de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11144","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 8 de agosto de 2012","modified":"Atualizado em 8 de agosto de 2012"},"absolute_dates_time":{"created":"Publicado em 8 de agosto de 2012 11:27","modified":"Atualizado em 8 de agosto de 2012 11:27"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11144"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11144\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}