{"id":11140,"date":"2012-08-01T17:17:48","date_gmt":"2012-08-01T20:17:48","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/08\/01\/senar-mt-prepara-o-futuro\/"},"modified":"2012-08-01T17:17:48","modified_gmt":"2012-08-01T20:17:48","slug":"senar-mt-prepara-o-futuro","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/08\/01\/senar-mt-prepara-o-futuro\/","title":{"rendered":"Senar-MT prepara o futuro"},"content":{"rendered":"<p>\nChegou a hora da sociedade rural apontar as principais necessidades encontradas nas propriedades em rela&ccedil;&atilde;o &agrave; qualifica&ccedil;&atilde;o da m&atilde;o de obra. Isso porque ter&aacute; inicio no m&ecirc;s de agosto o levantamento de demandas, junto aos sindicatos rurais e parceiros, por cursos e treinamentos para serem inseridas no Plano Anual do Trabalho (PAT) do Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT).<\/p>\n<p>\n&quot;Os supervisores das nove regionais do Senar ir&atilde;o realizar de 13 a 24 de agosto reuni&otilde;es com representantes dos sindicatos rurais, dos trabalhadores, da prefeitura, do com&eacute;rcio, das associa&ccedil;&otilde;es, assentamentos e demais setores para ouvirem deles quais os treinamentos que eles desejam que sejam realizados em seus munic&iacute;pios em 2013&quot;, explica o gerente de Aprendizagem Rural do Senar, Marciel Becker.<\/p>\n<p>\nSegundo Becker, no PAT aprovado no ano passado est&atilde;o previstos at&eacute; dezembro de 2012, 3500 treinamentos e 14 programas especiais, e a expectativa para o ano que vem &eacute; aumentar a demanda. &ldquo;O Senar tem a meta de qualificar 1 milh&atilde;o de pessoas at&eacute; 2020 e um dos gargalos da produ&ccedil;&atilde;o est&aacute; justamente na &aacute;rea de mecaniza&ccedil;&atilde;o agr&iacute;cola, o qual j&aacute; temos ind&iacute;cios de um procura maior em para 2013&rdquo;, revela o gerente. &quot;Al&eacute;m disso, estamos lan&ccedil;ando pelo menos cinco novos programas especiais que devem ser demandados para o pr&oacute;ximo ano, a exemplo do Filhos no Campo e Sucess&atilde;o Familiar&quot;, cita.<\/p>\n<p>\nAp&oacute;s as reuni&otilde;es nos munic&iacute;pios as solicita&ccedil;&otilde;es de treinamentos s&atilde;o consolidadas e apresentadas ao Senar-Central para aprova&ccedil;&atilde;o or&ccedil;ament&aacute;ria, s&oacute; depois dessa fase os cursos entram na programa&ccedil;&atilde;o do Senar de Mato Grosso.&nbsp; Se os presidentes de sindicatos preferirem, ainda, podem fazer a solicita&ccedil;&atilde;o de novos cursos pelo site do Sistema Famato, basta clicar <strong><a href=\"http:\/\/fws.senarmt.org.br\/reldemanda\/.\">aqui<\/a><\/strong>.<\/p>\n<p>\n&nbsp;O Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a nossa Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>). A institui&ccedil;&atilde;o de ensino rural est&aacute; presente em todos os munic&iacute;pios de Mato Grosso atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chegou a hora da sociedade rural apontar as principais necessidades encontradas nas propriedades em rela&ccedil;&atilde;o &agrave; qualifica&ccedil;&atilde;o da m&atilde;o de obra. Isso porque ter&aacute; inicio no m&ecirc;s de agosto o levantamento de demandas, junto aos sindicatos rurais e parceiros, por cursos e treinamentos para serem inseridas no Plano Anual do Trabalho (PAT) do Servi&ccedil;o Nacional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11140","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 1 de agosto de 2012","modified":"Atualizado em 1 de agosto de 2012"},"absolute_dates_time":{"created":"Publicado em 1 de agosto de 2012 17:17","modified":"Atualizado em 1 de agosto de 2012 17:17"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11140"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11140\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}