{"id":11138,"date":"2012-07-20T12:46:44","date_gmt":"2012-07-20T15:46:44","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/07\/20\/novas-oportunidades-de-qualificacao-rural-em-mato-grosso\/"},"modified":"2012-07-20T12:46:44","modified_gmt":"2012-07-20T15:46:44","slug":"novas-oportunidades-de-qualificacao-rural-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/07\/20\/novas-oportunidades-de-qualificacao-rural-em-mato-grosso\/","title":{"rendered":"Novas oportunidades de qualifica\u00e7\u00e3o rural em Mato Grosso"},"content":{"rendered":"<p>\nSemanalmente o Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) oferece uma m&eacute;dia de mil vagas em treinamentos gratuitos voltados para as atividades do campo. Entre os dias 23 e 28 de julho ser&atilde;o ofertados 89 treinamentos, abrindo 1496 oportunidades de qualifica&ccedil;&atilde;o em 51 munic&iacute;pios mato-grossenses. &quot;Piscicultura&quot;, &quot;Insemina&ccedil;&atilde;o artificial em bovinos&quot; e &quot;Manejo e recupera&ccedil;&atilde;o de pastagens&quot; s&atilde;o alguns dos cursos programados para ocorrer nesse per&iacute;odo.<\/p>\n<p>\nTodos os treinamentos s&atilde;o realizados em parceria com os sindicatos rurais e\/ou prefeituras, respons&aacute;veis pela mobiliza&ccedil;&atilde;o das pessoas que receber&atilde;o a capacita&ccedil;&atilde;o. Cada turma &eacute; formada, em m&eacute;dia, por 15 alunos, sempre tendo como p&uacute;blico-alvo produtores, trabalhadores rurais e seus familiares. A mobiliza&ccedil;&atilde;o das turmas est&aacute; sob a responsabilidade dos sindicatos rurais ou das prefeituras onde n&atilde;o existem sindicatos.<\/p>\n<p>\nOs munic&iacute;pios beneficiados dessa vez s&atilde;o: Alto Gar&ccedil;as, Alto Paraguai, Alto Taquari, Apiac&aacute;s, Araputanga, Aren&aacute;polis, Aripuan&atilde;, C&aacute;ceres, Campin&aacute;polis, Campo Novo do Parecis, Campos de J&uacute;lio, Carlinda, Colniza, Comodoro, Cuiab&aacute;, Curvel&acirc;ndia, Diamantino, Dom Aquino, Guarant&atilde; do Norte, Guiratinga, Indiavai, Jaciara, Juara, Juina, Lucas do Rio Verde, Matup&aacute;, Nova Bandeirantes, Nova Brasil&acirc;ndia, Nova Lacerda, Nova Xavantina, Novo Mundo, Paranaita, Paranatinga, Pocon&eacute;, Ponte Branca, Porto Esperidi&atilde;o, Poxoreo, Primavera do Leste, Ribeir&atilde;o Cascalheira, Rio Branco, Rondon&oacute;polis, Ros&aacute;rio Oeste, Salto do C&eacute;u, Santa Rita do Trivelato, Santo Antonio de Leverger, S&atilde;o Felix do Araguaia, S&atilde;o Jose do Rio Claro, S&atilde;o Jose do Xingu, Sinop, Sorriso e Tangara da Serra.<\/p>\n<p>\nPara saber quais cursos ser&atilde;o realizados em cada munic&iacute;pio acesse o menu &quot;Cursos Programados&quot; no site <a href=\"http:\/\/www.sistemafamato.org.br\/senar\/\" target=\"_blank\" rel=\"noopener\">www.senarmt.org.br<\/a>. L&aacute; tamb&eacute;m &eacute; poss&iacute;vel encontrar os telefones dos Sindicatos Rurais ou prefeituras respons&aacute;veis pela forma&ccedil;&atilde;o das turmas.<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#%21\/senar_mt\" target=\"_blank\" rel=\"noopener\">@senar_mt<\/a> e curta a nossa Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/SenarMt<\/a>). A institui&ccedil;&atilde;o de ensino rural est&aacute; presente em todos os munic&iacute;pios de Mato Grosso atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso &#8211; entidade e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Semanalmente o Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) oferece uma m&eacute;dia de mil vagas em treinamentos gratuitos voltados para as atividades do campo. Entre os dias 23 e 28 de julho ser&atilde;o ofertados 89 treinamentos, abrindo 1496 oportunidades de qualifica&ccedil;&atilde;o em 51 munic&iacute;pios mato-grossenses. &quot;Piscicultura&quot;, &quot;Insemina&ccedil;&atilde;o artificial em bovinos&quot; e &quot;Manejo e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11138","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 20 de julho de 2012","modified":"Atualizado em 20 de julho de 2012"},"absolute_dates_time":{"created":"Publicado em 20 de julho de 2012 12:46","modified":"Atualizado em 20 de julho de 2012 12:46"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11138"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11138\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}