{"id":11134,"date":"2012-07-13T15:24:35","date_gmt":"2012-07-13T18:24:35","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/07\/13\/abertas-1520-vagas-para-cursos-gratuitas-em-53-municipios-de-mt\/"},"modified":"2012-07-13T15:24:35","modified_gmt":"2012-07-13T18:24:35","slug":"abertas-1520-vagas-para-cursos-gratuitas-em-53-municipios-de-mt","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/07\/13\/abertas-1520-vagas-para-cursos-gratuitas-em-53-municipios-de-mt\/","title":{"rendered":"Abertas 1520 vagas para cursos gratuitas em 53 munic\u00edpios de MT"},"content":{"rendered":"<p>\nAs oficinas de &quot;Beneficiamento e Conserva&ccedil;&atilde;o de Pescado&quot; e de &quot;Manuten&ccedil;&atilde;o de Tratores Agr&iacute;colas&quot; ser&atilde;o os dois &uacute;ltimos treinamentos realizados pelo Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), na noite de s&aacute;bado (14.07), durante a 48&ordf; Exposi&ccedil;&atilde;o Internacional, Agropecu&aacute;ria, Industrial e Comercial de Mato Grosso (Expoagro). Al&eacute;m dessas oficinas at&eacute; o pr&oacute;ximo s&aacute;bado ser&atilde;o 92 treinamentos ofertados pela institui&ccedil;&atilde;o em parceria com os sindicatos rurais e\/ou prefeituras.<\/p>\n<p>\nNessa semana estar&atilde;o abertas 1520 vagas em 53 munic&iacute;pios do Estado. Os treinamentos s&atilde;o uma oportunidade de qualifica&ccedil;&atilde;o profissional gratuita e dentre os cursos ofertados est&aacute; &quot;Manuten&ccedil;&atilde;o e Regulagem de Colheitadeiras&quot;, &quot;Piscicultura&quot; e &quot;Alternativa de Alimenta&ccedil;&atilde;o para bovinos no per&iacute;odo da seca&quot;, entre outros cursos dispon&iacute;veis. Cada turma &eacute; formada, em m&eacute;dia, por 15 alunos e o p&uacute;blico-alvo s&atilde;o produtores, trabalhadores rurais e seus familiares. A mobiliza&ccedil;&atilde;o das turmas est&aacute; sob a responsabilidade dos sindicatos rurais ou das prefeituras onde n&atilde;o existem sindicatos.<\/p>\n<p>\nOs munic&iacute;pios beneficiados s&atilde;o: Alta Floresta, Alto Araguaia, Alto Gar&ccedil;as, Apiacas, Araputanga, Aripuana, Brasnorte, C&aacute;ceres, Campo Verde, Canarana, Carlinda, Castanheira, Chapada dos Guimar&atilde;es, Cl&aacute;udia, Cocalinho, Colider, Colniza, Confresa, Cuiab&aacute;, Denise, Diamantino, Guarant&atilde; do Norte, Guiratinga, Itiquira, Juara, Juruena, Juscimeira, Matup&aacute;, Nova Bandeirantes, Nova Cana&atilde; do Norte, Nova Lacerda, Nova Ubirat&atilde;, Paranaita, Paranatinga, Pocon&eacute;, Pontes e Lacerda, Porto Esperidi&atilde;o, Porto Estrela, Primavera do Leste, Quer&ecirc;ncia, Rio Branco, Rondon&oacute;polis, Santo Antonio de Leverger, S&atilde;o Felix do Araguaia, S&atilde;o Jos&eacute; do Povo, S&atilde;o Jos&eacute; dos Quatro Marcos, Sinop, Sorriso, Tabapor&atilde;, Tangar&aacute; da Serra, Tesouro, Vila Bela da Sant&iacute;ssima Trindade e Vila Rica.<\/p>\n<p>\nPara saber quais cursos ser&atilde;o realizados em cada munic&iacute;pio acesse o menu &quot;Cursos Programados&quot; no site <a href=\"http:\/\/www.sistemafamato.org.br\/senar\/\">www.senarmt.org.br<\/a>. L&aacute; tamb&eacute;m &eacute; poss&iacute;vel encontrar os telefones dos Sindicatos Rurais ou prefeituras respons&aacute;veis pela forma&ccedil;&atilde;o das turmas.<\/p>\n<p>\nEstamos no Twitter e no Facebook. Siga <a href=\"https:\/\/twitter.com\/#!\/senar_mt\">@senar_mt<\/a>&nbsp; e curta a nossa Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\">http:\/\/www.facebook.com\/SenarMt<\/a>).<\/p>\n<p>\nO Senar-MT &eacute; uma institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso &#8211; entidade e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As oficinas de &quot;Beneficiamento e Conserva&ccedil;&atilde;o de Pescado&quot; e de &quot;Manuten&ccedil;&atilde;o de Tratores Agr&iacute;colas&quot; ser&atilde;o os dois &uacute;ltimos treinamentos realizados pelo Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), na noite de s&aacute;bado (14.07), durante a 48&ordf; Exposi&ccedil;&atilde;o Internacional, Agropecu&aacute;ria, Industrial e Comercial de Mato Grosso (Expoagro). Al&eacute;m dessas oficinas at&eacute; o pr&oacute;ximo s&aacute;bado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11134","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 13 de julho de 2012","modified":"Atualizado em 13 de julho de 2012"},"absolute_dates_time":{"created":"Publicado em 13 de julho de 2012 15:24","modified":"Atualizado em 13 de julho de 2012 15:24"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11134"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11134\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}