{"id":11125,"date":"2012-07-04T16:00:25","date_gmt":"2012-07-04T19:00:25","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/07\/04\/senar-mt-qualificara-200-pessoas-em-10-dias-de-feira\/"},"modified":"2012-07-04T16:00:25","modified_gmt":"2012-07-04T19:00:25","slug":"senar-mt-qualificara-200-pessoas-em-10-dias-de-feira","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/07\/04\/senar-mt-qualificara-200-pessoas-em-10-dias-de-feira\/","title":{"rendered":"Senar-MT qualificar\u00e1 200 pessoas em 10 dias de feira"},"content":{"rendered":"<p>\nTer\u00e1 in\u00edcio na noite de quinta-feira (05.07) a 48\u00aa Exposi\u00e7\u00e3o Internacional, Agropecu\u00e1ria, Industrial e Comercial de Mato Grosso (Expoagro). O evento segue at\u00e9 o dia 15 de julho no Parque de Exposi\u00e7\u00f5es Jonas Pinheiro, \u00e9 organizado pelo Sindicato Rural de Cuiab\u00e1. Esta \u00e9 considerada a maior exposi\u00e7\u00e3o agropecu\u00e1ria do Centro-Oeste e o Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT), como nos anos anteriores, manter\u00e1 um stand no local, onde ser\u00e3o divulgadas a\u00e7\u00f5es da entidade em todo o Estado.<\/p>\n<p>\nNo stand ser\u00e3o realizadas oficinas gratuitas baseadas nos cursos desenvolvidos pela institui\u00e7\u00e3o rural. Ser\u00e3o oferecidas 20 oficinas de qualifica\u00e7\u00e3o, sendo 10 de beneficiamento de carnes (pescado, frango e carneiro) e 10 de manuten\u00e7\u00e3o de m\u00e1quinas agr\u00edcolas. Os treinamentos s\u00e3o gratuitos e qualificar\u00e3o ao todo 200 pessoas. &#8220;As oficinas ocorrem no per\u00edodo noturno em salas preparadas para o treinamento de beneficiamento de carnes. Tamb\u00e9m teremos um trator, conseguido por meio de parceria com o Sindicato Rural e a empresa representante do maquin\u00e1rio, para as oficinas de mecaniza\u00e7\u00e3o agr\u00edcola&#8221;, informou o supervisor do Senar da Regional de Cuiab\u00e1, Natalino M\u00e1rcio Viana da Costa. &#8220;As pessoas interessadas podem buscar informa\u00e7\u00f5es no pr\u00f3prio stand do Senar das 18h00 at\u00e9 \u00e0s 23h00&#8221;, acrescentou.<\/p>\n<p>\nNeste ano ser\u00e1 realizado ainda o pr\u00e9-lan\u00e7amento do Programa Especial do Senar Filhos no Campo, que vai ocorrer no pr\u00f3ximo m\u00eas em um shopping da Capital, com intuito de aproximar a sociedade urbana do cotidiano rural.<\/p>\n<p>\nO Senar-MT \u00e9 uma institui\u00e7\u00e3o de ensino rural e faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso &#8211; entidade que congrega e representa os 86 Sindicatos Rurais &#8211; e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea-MT).<\/p>\n<p>\n<strong>Programa\u00e7\u00e3o \u2013 <\/strong>A organiza\u00e7\u00e3o do evento prev\u00ea que cerca de 300 mil pessoas circulem pelo Parque de Exposi\u00e7\u00e3o durante os dias de Expoagro. Consta na programa\u00e7\u00e3o leil\u00f5es de gado leiteiro e de corte, 28 shows musicais, rodeio, prova de hipismo cl\u00e1ssico, dos tr\u00eas tambores, Horse Cross com o cavalo \u00c1rabe, prova de la\u00e7o comprido como o cavalo Pantaneiro, torneio leiteiro, julgamento do cavalo \u00c1rabe, do Gir Leiteiro, Girolando, ovinos e Ranking da Ra\u00e7a Nelore &#8211; MT. Outras informa\u00e7\u00f5es podem ser obtidas pelo site: <a href=\"http:\/\/www.sindruralcuiaba.org.br\/\">http:\/\/www.sindruralcuiaba.org.br<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ter\u00e1 in\u00edcio na noite de quinta-feira (05.07) a 48\u00aa Exposi\u00e7\u00e3o Internacional, Agropecu\u00e1ria, Industrial e Comercial de Mato Grosso (Expoagro). O evento segue at\u00e9 o dia 15 de julho no Parque de Exposi\u00e7\u00f5es Jonas Pinheiro, \u00e9 organizado pelo Sindicato Rural de Cuiab\u00e1. Esta \u00e9 considerada a maior exposi\u00e7\u00e3o agropecu\u00e1ria do Centro-Oeste e o Servi\u00e7o Nacional de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11125","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 4 de julho de 2012","modified":"Atualizado em 4 de julho de 2012"},"absolute_dates_time":{"created":"Publicado em 4 de julho de 2012 16:00","modified":"Atualizado em 4 de julho de 2012 16:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11125"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11125\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}