{"id":11121,"date":"2012-06-27T15:55:38","date_gmt":"2012-06-27T18:55:38","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/06\/27\/senar-lanca-programa-em-mato-grosso\/"},"modified":"2012-06-27T15:55:38","modified_gmt":"2012-06-27T18:55:38","slug":"senar-lanca-programa-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/06\/27\/senar-lanca-programa-em-mato-grosso\/","title":{"rendered":"Senar lan\u00e7a programa em Mato Grosso"},"content":{"rendered":"<p>\nDurante seis meses um microonibus adaptado com 11 computadores ir&aacute; acompanhar o Programa Mutir&atilde;o Rural da Cidadania, realizado pelo Servi&ccedil;o Nacional de Aprendizagem Rural (Senar-MT) em parceria com a Secretaria de Estado de Assist&ecirc;ncia Social (Setas).&nbsp; Trata-se do Programa Especial <em>Inclus&atilde;o Digital Rural<\/em>, lan&ccedil;ado oficialmente nessa quarta-feira (27.06), no estacionamento da Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato), em Cuiab&aacute;, pelo presidente do Senar-MT, Rui Prado e pelo superintendente da institui&ccedil;&atilde;o, Tiago Mattosinho. &quot;Queremos levar essa sala de aula sobre rodas para as comunidades rurais mais distantes poss&iacute;veis, e com isso levar a oportunidade para quem vive fora dos centros urbanos de acessar a microcomputadores e a internet, algo t&atilde;o comum para quem est&aacute; na cidade, mas que n&atilde;o &eacute; a realidade para quem vive no campo&quot;, afirmou Prado.<\/p>\n<p>\nDe acordo com o superintendente do Senar, essa sala de aula itinerante atender&aacute; produtores, trabalhadores rurais e seus familiares nas propriedades do Estado de Mato Grosso. Mattosinho explica que o microonibus foi disponibilizado pelo Senar Central (Bras&iacute;lia) e tem o objetivo de levar no&ccedil;&otilde;es b&aacute;sicas de inform&aacute;tica ao meio rural, permitindo assim que o p&uacute;blico alvo da institui&ccedil;&atilde;o tenha acesso a esse recurso tecnol&oacute;gico. &quot;O programa visa despertar na popula&ccedil;&atilde;o do meio rural o interesse pelos recursos digitais hoje t&atilde;o difundidos em outros setores da sociedade como e-mail, sites de not&iacute;cias, informa&ccedil;&otilde;es e sites com conte&uacute;dos voltados para os produtores e trabalhadores rurais&rdquo;, afirmou. &ldquo;Eles percebem o quanto estas ferramentas podem auxiliar em suas atividades e at&eacute; mesmo propiciar uma melhoria na qualidade de vida &agrave; medida que facilita o acesso a educa&ccedil;&atilde;o&quot;, completou.<\/p>\n<p>\nNa solenidade de lan&ccedil;amento os alunos do programa piloto, formada por integrantes do Assentamento Gamaliel &#8211; Zona Rural de Cuiab&aacute;, receberam o certificado de conclus&atilde;o de curso. O aposentado Edson Moraes, 68, era o mais animado. &quot;Agora que perdi o medo do computador pretendo continuar a estudar inform&aacute;tica, n&atilde;o d&aacute; para ficar parado&quot;, disse. A dona de casa Avelina Martins, 60, tamb&eacute;m recebeu o seu certificado e agradeceu ao Senar pela oportunidade. &quot;J&aacute; posso ter meu e-mail para conversar com familiares e amigos que est&atilde;o longe&quot;, planejou. &quot;O programa &eacute; maravilhoso porque muda a vis&atilde;o da zona rural. Antes quando se falava em meio rural j&aacute; vinha na cabe&ccedil;a enxada e foice, agora estamos na era no teclado&quot;, filosofou.<\/p>\n<p>\nAproveitando o microonibus estacionado outra turma da comunidade Gamaliel participou de uma oficina de quatro horas. Nesse treinamento os alunos tiveram a oportunidade de ter contado com o computador, saber os benef&iacute;cios da inform&aacute;tica, os utilit&aacute;rios, o surgimento da internet e at&eacute; criar um e-mail. &quot;Esse &eacute; o primeiro contato deles com a m&aacute;quina, o objetivo &eacute; derrubar o mito de que qualquer coisa pode estragar o computador. Depois eles tiveram uma aula bem b&aacute;sica para quem j&aacute; convive com a ferramenta, mas de muita valia para eles&quot;, revelou o instrutor do Senar, Paulo Henrique da Silva.<\/p>\n<p>\nNo m&ecirc;s de julho o microonibus acompanha o Mutir&atilde;o Rural da Cidadania nos eventos que ocorrem nos munic&iacute;pios de Alto Taquari, Alto Araguaia, Alto Gar&ccedil;as, Ribeir&atilde;ozinho, Ponte Branca, Araguainha, Pedra Preta, Rondonopolis, Itiquira, Tesouro, Guiratinga, S&atilde;o Jose Do Povo, Juscimeira, Dom Aquino e Jaciara.<\/p>\n<p>\n<strong>Cases M&oacute;veis &ndash; <\/strong>Al&eacute;m do microonibus, que permanece em Mato Grosso at&eacute; novembro, o Senar-MT possui cinco <em>Cases M&oacute;veis<\/em> (malas), com 10 notebooks cada, para realiza&ccedil;&atilde;o de aulas de inform&aacute;tica em salas disponibilizados pelos sindicatos rurais. Cada <em>case<\/em> permanece de dois a tr&ecirc;s meses em cada regional. Nessa modalidade os treinamentos podem ser de quatro, oito ou 16 horas, dependendo do objetivo da turma formada. As turmas com carga hor&aacute;ria de 16 horas receber&atilde;o conte&uacute;dos como apresenta&ccedil;&atilde;o dos hardwares, Pacote Office, internet, cria&ccedil;&atilde;o de e-mail, navega&ccedil;&atilde;o pelo Canal do Produtor. Nas turmas de carga hor&aacute;ria de oito horas s&atilde;o fornecidos os mesmos conte&uacute;dos, mas com &ecirc;nfase no uso da internet. J&aacute; nas que t&ecirc;m carga de quatro horas, a &ecirc;nfase se d&aacute; no uso da internet.<\/p>\n<p>\nOs sindicatos rurais podem solicitar o Programa Especial <em>Inclus&atilde;o Digital Rural<\/em> &#8211; Cases M&oacute;veis ao Senar-MT e &nbsp;a programa&ccedil;&atilde;o ser&aacute; feita de acordo com a log&iacute;stica da regional. Nesse m&ecirc;s as malas est&atilde;o no Sindicato Rural de Campo Verde. &quot;A procura est&aacute; sendo muito boa e temos turmas agendadas at&eacute; setembro&quot;, afirma o presidente do sindicato, Luiz Fernando Silva Guerreiro.<\/p>\n<p>\nO Senar-MT &eacute; uma institui&ccedil;&atilde;o de ensino rural, que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (Imea-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante seis meses um microonibus adaptado com 11 computadores ir&aacute; acompanhar o Programa Mutir&atilde;o Rural da Cidadania, realizado pelo Servi&ccedil;o Nacional de Aprendizagem Rural (Senar-MT) em parceria com a Secretaria de Estado de Assist&ecirc;ncia Social (Setas).&nbsp; Trata-se do Programa Especial Inclus&atilde;o Digital Rural, lan&ccedil;ado oficialmente nessa quarta-feira (27.06), no estacionamento da Federa&ccedil;&atilde;o da Agricultura e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11121","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 27 de junho de 2012","modified":"Atualizado em 27 de junho de 2012"},"absolute_dates_time":{"created":"Publicado em 27 de junho de 2012 15:55","modified":"Atualizado em 27 de junho de 2012 15:55"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11121"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11121\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}