{"id":11091,"date":"2012-05-14T16:15:58","date_gmt":"2012-05-14T19:15:58","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/05\/14\/projeto-filantropico-ajuda-na-reabilitacao\/"},"modified":"2012-05-14T16:15:58","modified_gmt":"2012-05-14T19:15:58","slug":"projeto-filantropico-ajuda-na-reabilitacao","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/05\/14\/projeto-filantropico-ajuda-na-reabilitacao\/","title":{"rendered":"Projeto filantr\u00f3pico ajuda na reabilita\u00e7\u00e3o"},"content":{"rendered":"<p>\nNo \u00faltimo domingo comemorou-se o Dia das M\u00e3es, mas para a dona de casa M\u00e1rcia Maria de Barros, 33, o presente chegou h\u00e1 dois meses, quando o filho dela, Luiz Fernando Barros de Amorim, de seis anos, come\u00e7ou a demonstrar afetividade com sorrisos, trocas de olhar e carinhos. Gestos comuns em crian\u00e7as desta idade, mas raros em um autista. Nando, como \u00e9 chamado pela m\u00e3e, foi diagnosticado aos dois anos de idade, depois que M\u00e1rcia, que tem outros quatro filhos, percebeu que ele era diferente dos demais.<\/p>\n<p>\n&#8220;Com dois anos meus outros filhos j\u00e1 falavam, mas o Nando n\u00e3o. Eu chamava por ele, mas ele n\u00e3o respondia, sempre queria brincar sozinho, n\u00e3o reclamava de nada&#8221;, lembra.<\/p>\n<p>\nFoi ent\u00e3o que M\u00e1rcia buscou ajuda profissional. Procurou um neurologista, que diagnosticou Nando como portador de S\u00edndrome de Autismo. O m\u00e9dico encaminhou o menino para tratamento no Centro de Aten\u00e7\u00e3o Psicossocial Infantil (CAPSI), unidade estadual de sa\u00fade. L\u00e1 a m\u00e3e recebeu orienta\u00e7\u00f5es de como cuidar do filho especial. &#8220;Eu trabalhava como auxiliar de limpeza, mas tive que deixar o emprego para ficar tempo integral com o meu filho. Ele precisa de cuidados 24 horas por dia&#8221;, afirma.<\/p>\n<p>\nO presente do Dia das M\u00e3es de M\u00e1rcia chegou quando ela conseguiu uma das 15 vagas disponibilizadas pelo projeto de Equoterapia desenvolvido pelo Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) em parceria com o Espa\u00e7o H\u00edpico Rancho Dourado, em Cuiab\u00e1. A coordenadora da equipe de Pedagogia do Senar-MT, Tatiana Perondi, explica que o projeto de Equoterapia \u00e9 filantr\u00f3pico e por meio dele o Senar visa proporcionar ao indiv\u00edduo o desenvolvimento de suas potencialidades, respeitando seus limites e visando sua integra\u00e7\u00e3o na sociedade.<\/p>\n<p>\n&#8220;O projeto s\u00f3 pode funcionar por meio de parceria entre o Senar e os Centros H\u00edpicos, Sindicatos Rurais e\/ou Associa\u00e7\u00f5es de Pais e Amigos dos Excepcionais (APAEs). Para esse atendimento acontecer o Senar entra com uma ajuda de custo e o parceiro com a estrutura necess\u00e1ria&#8221;, completa.<\/p>\n<p>\nO Espa\u00e7o H\u00edpico Rancho Dourado definiu que iria disponibilizar um dia da semana, \u00e0s quartas-feiras, para atender os 15 benefici\u00e1rios do projeto. Cada um participa de sess\u00f5es de 30 minutos com o cavalo e mais dois ou tr\u00eas integrantes de equipe disciplinar formada por fisioterapeuta, fonoaudi\u00f3logo, psicopedagoga, psic\u00f3logo e auxiliares de pista. Nando chegou quieto, alheio ao ambiente a sua volta. Ao subir na \u00e9gua <em>Lady<\/em>, deu o primeiro sorriso demonstrando que estava pronto para a sess\u00e3o de equoterapia. &#8220;Ele s\u00f3 aceitou subir no cavalo no terceiro dia, agora j\u00e1 vem todo animado&#8221;, afirma a m\u00e3e empolgada.<\/p>\n<p>\nEm apenas 60 dias, M\u00e1rcia j\u00e1 percebeu que Nando estava mais tranquilo, come\u00e7ava a interagir com as pessoas e demonstrar interesse pelo cavalo. &#8220;Como ele n\u00e3o fala, percebo os sentimentos dele pela express\u00e3o. Quando digo que \u00e9 hora de ver o cavalo, ele j\u00e1 muda a express\u00e3o&#8221;. E completa: &#8220;Meu filho est\u00e1 se desenvolvendo. Estou muito feliz. N\u00e3o deixo de vir \u00e0s sess\u00f5es&#8221;, diz ao lembrar que para o filho participar da sess\u00e3o, eles que moram no bairro Parque Sabi\u00e1, em V\u00e1rzea Grande, precisam pegar dois \u00f4nibus e caminhar mais 15 minutos at\u00e9 a h\u00edpica, s\u00e3o quase duas horas de trajeto.<\/p>\n<p>\nDe acordo com a psic\u00f3loga da equipe multidisciplinar que acompanha o tratamento de Nando, Andrea Amude, a percep\u00e7\u00e3o da m\u00e3e em rela\u00e7\u00e3o ao tratamento do filho est\u00e1 correta. &#8220;Estamos percebendo essas melhoras no Nando. O que \u00e9 muito positivo. Com apenas dois meses a evolu\u00e7\u00e3o apresentada por ele \u00e9 muito r\u00e1pida&#8221;, avalia. Para a profissional o principal progresso apresentado pelo menino foi em rela\u00e7\u00e3o \u00e0 afetividade. &#8220;Sabemos que os autistas t\u00eam dificuldades de intera\u00e7\u00e3o social e durante a \u00faltima sess\u00e3o Nando passou a m\u00e3o na minha cabe\u00e7a e puxou para perto dele. Isso para uma crian\u00e7a que tem autismo \u00e9 uma evolu\u00e7\u00e3o tremenda&#8221;, compartilha a psic\u00f3loga.<\/p>\n<p>\nO fisioterapeuta Daniel Penha, integrante da equipe multidisciplinar do projeto, explica que a \u00fanica exig\u00eancia para a pr\u00e1tica da equoterapia \u00e9 que haja uma recomenda\u00e7\u00e3o m\u00e9dica, pois n\u00e3o h\u00e1 limite de idade e as indica\u00e7\u00f5es da equoterapia s\u00e3o para tratamentos de outras patologias como para pessoas acometidas por paralisia cerebral, Acidente Vascular Cerebral (AVC), problemas neurol\u00f3gicos ou f\u00edsicos, les\u00f5es t\u00f3raco-lombares, dist\u00farbios psicol\u00f3gicos, dist\u00farbios mentais, esquizofrenia, depress\u00e3o, transtorno de ansiedade, S\u00edndrome do P\u00e2nico, entre outras. &#8220;Muitos pais que n\u00e3o t\u00eam a informa\u00e7\u00e3o sobre a equoterapia acham que os filhos deles v\u00e3o chegar aqui e simplesmente dar &#8216;uma voltinha a cavalo&#8217;. Mas, com o tempo e com o tratamento eles veem a evolu\u00e7\u00e3o dos praticantes e percebem o quanto a equoterapia \u00e9 importante, percebem o quanto os filhos melhoram com o tratamento&#8221;, argumenta.<\/p>\n<p>\nA propriet\u00e1ria da h\u00edpica, Ana Julieta Pompeu de Barros, diz que nestes tr\u00eas anos de parceria com o Senar j\u00e1 realizou mais de dois mil atendimentos gratuitos voltados \u00e0 popula\u00e7\u00e3o de baixa renda. Durante esse per\u00edodo, muitas m\u00e3es tiveram a felicidade de ver seus filhos apresentando melhoras como a experi\u00eancia que pela qual M\u00e1rcia est\u00e1 passando. &#8220;As m\u00e3es que conseguem uma vaga para o tratamento de seu filho ficam devotas da equoterapia, ficam gratas pela melhora que os filhos apresentam de forma t\u00e3o r\u00e1pida. As m\u00e3es ficam realmente impressionadas e fazem propaganda boca a boca. Tenho uma fila de espera com mais de 300 pessoas&#8221;, contabiliza.<\/p>\n<p>\nM\u00e1rcia conta que o pai de Nando, Roney Amorim da Silva, 27, \u00e9 frentista de posto de gasolina e que sem o sal\u00e1rio de auxiliar de limpeza que ela recebia o or\u00e7amento familiar ficou apertado. &#8220;Eu jamais teria condi\u00e7\u00f5es de manter meu filho na equoterapia. Eu n\u00e3o posso trabalhar para poder cuidar dele. Se n\u00e3o fosse o projeto eu n\u00e3o estaria aqui e ele n\u00e3o teria essa evolu\u00e7\u00e3o. Agrade\u00e7o muito por ter esse projeto em nossas vidas&#8221;, diz.<\/p>\n<p>\n&#8220;A equoterapia \u00e9 uma terapia cara, por envolver um animal como o cavalo, gasta-se muito com a manuten\u00e7\u00e3o. Al\u00e9m disso sempre temos dois profissionais, pelo menos, acompanhando cada praticante. Sabemos que poucas pessoas tem acesso ao tratamento privado&#8221;, informa a psic\u00f3loga. &#8220;O projeto do Senar possibilita que nossos praticantes de quarta-feira possam ter um tratamento que eles jamais teriam, j\u00e1 que por m\u00eas o custo seria em torno de R$ 300. O valor acaba dificultando o acesso&#8221;, cita.<\/p>\n<p>\nO fisioterapeuta Daniel Penha acredita que o conv\u00eanio com o Senar contribui para deselitizar a equoterapia, ampliando o tratamento para pessoas com poder aquisitivo menor. &#8220;Essa parceria veio em boa hora. \u00c9 gratificante ver a melhora de cada um que vem aqui&#8221;, afirma.<\/p>\n<p>\nA psic\u00f3loga Andrea ainda ressalta: &#8220;Ap\u00f3s ver a evolu\u00e7\u00e3o deles \u00e9 uma realiza\u00e7\u00e3o e sem esse projeto essa evolu\u00e7\u00e3o n\u00e3o seria poss\u00edvel&#8221;.<\/p>\n<p>\nO Senar-MT \u00e9 uma institui\u00e7\u00e3o de ensino rural, vinculada a Confedera\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Brasil (CNA). Est\u00e1 presente em todos os munic\u00edpios de Mato Grosso atuando em parceria com os 86 sindicatos rurais e prefeituras onde n\u00e3o h\u00e1 sindicato, faz parte do Sistema Famato, assim como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Mato Grosso e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea-MT).<\/p>\n<p>\n<strong>PROJETO<\/strong> \u2013 O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso \u00e9 o \u00fanico Senar do Brasil que oferece o projeto de Equoterapia como uma das atividades do Programa Especial Apoena, que na l\u00edngua tupi-guarani quer dizer &#8220;aquele que enxerga longe&#8221;. O programa tem por objetivo a qualifica\u00e7\u00e3o de pessoas com necessidades especiais, estimulando a participa\u00e7\u00e3o de deficientes nos cursos ofertados pela institui\u00e7\u00e3o. Todo Senar segue o programa da institui\u00e7\u00e3o sediada em Bras\u00edlia (Senar Central), mas tem autonomia para definir projetos pr\u00f3prios. A equoterapia consiste em um m\u00e9todo terap\u00eautico e educacional, que utiliza o cavalo, dentro de uma abordagem interdisciplinar. As atividades s\u00e3o desenvolvidas pela equipe multidisciplinar.<\/p>\n<p>\nDe acordo com o supervisor do Senar-MT, Rodrigo Fischdick, respons\u00e1vel projeto de Equoterapia no Estado, a primeira parceria foi firmada em janeiro de 2007 com o Centro Equestre e de Equoterapia de V\u00e1rzea Grande. Atualmente, o Senar-MT mant\u00e9m oito conv\u00eanios, sendo dois em Cuiab\u00e1 (Rancho Dourado e o Centro H\u00edpico de Cuiab\u00e1), em Santo Antonio do Leverger (parceria com o Sindicato Rural), em Lucas do Rio Verde, em Tangar\u00e1 da Serra, em Sorriso e em Sinop, onde os conv\u00eanios foram assinados com as Apaes locais. Cada um dos parceiros tem a meta de atender 15 praticantes por m\u00eas. Em 2011, por meio dessas parcerias foram oferecidos 3038 atendimentos de Equoterapia, atingindo 1.298 pessoas no Estado.<\/p>\n<p>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo domingo comemorou-se o Dia das M\u00e3es, mas para a dona de casa M\u00e1rcia Maria de Barros, 33, o presente chegou h\u00e1 dois meses, quando o filho dela, Luiz Fernando Barros de Amorim, de seis anos, come\u00e7ou a demonstrar afetividade com sorrisos, trocas de olhar e carinhos. Gestos comuns em crian\u00e7as desta idade, mas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11091","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 14 de maio de 2012","modified":"Atualizado em 14 de maio de 2012"},"absolute_dates_time":{"created":"Publicado em 14 de maio de 2012 16:15","modified":"Atualizado em 14 de maio de 2012 16:15"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11091"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11091\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}