{"id":11046,"date":"2012-03-13T15:21:04","date_gmt":"2012-03-13T18:21:04","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/03\/13\/rui-prado-integra-conselho-deliberativo-do-senar-nacional\/"},"modified":"2012-03-13T15:21:04","modified_gmt":"2012-03-13T18:21:04","slug":"rui-prado-integra-conselho-deliberativo-do-senar-nacional","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/03\/13\/rui-prado-integra-conselho-deliberativo-do-senar-nacional\/","title":{"rendered":"Rui Prado integra Conselho Deliberativo do Senar Nacional"},"content":{"rendered":"<p>\nO presidente do Sistema Famato\/Senar, Rui Prado, \u00e9 o novo membro titular do Conselho Deliberativo do Servi\u00e7o Nacional de Aprendizagem Rural Nacional em Bras\u00edlia (Senar Central) no tri\u00eanio 2012\/2014.\u00a0 Prado foi indicado pela presidente do Conselho Nacional de Agricultura (CNA), senadora K\u00e1tia Abreu, no in\u00edcio do m\u00eas. Nessa quinta-feira (15.03), \u00e0s 9h, ele ir\u00e1 participar da 64\u00aa reuni\u00e3o Ordin\u00e1ria do Conselho.<\/p>\n<p>\nRui Prado ir\u00e1 integrar as Comiss\u00f5es Tem\u00e1ticas que analisar\u00e3o a Presta\u00e7\u00e3o de Contas do Exerc\u00edcio de 2011 e o Relat\u00f3rio de Atividades de 2011. &#8220;Mato Grosso \u00e9 um estado em desenvolvimento, que necessita de capacita\u00e7\u00e3o profissional e o Senar-MT tem feito a\u00a0 diferen\u00e7a, atendendo essas demandas&#8221;, aponta Prado. &#8220;A representa\u00e7\u00e3o de Mato Grosso no Conselho d\u00e1 a dimens\u00e3o do trabalho que vem sendo feito pelo Senar-MT&#8221;, acrescenta.<\/p>\n<p>\n&#8220;O convite para integrar o Conselho Deliberativo o Senar Nacional representa para n\u00f3s o reconhecimento do processo de profissionaliza\u00e7\u00e3o das institui\u00e7\u00f5es do nosso Sistema Famato\/Senar e IMEA, desenvolvido pelo presidente Rui Prado&#8221;, avaliou o superintendente do Senar-MT, Tiago Mattosinho\u00a0\u00a0<\/p>\n<p>\nEm m\u00e9dia, o Senar capacita 42 mil pessoas por ano, seja em cursos de Forma\u00e7\u00e3o Profissional Rural ou em a\u00e7\u00f5es de Promo\u00e7\u00e3o Social. Ao lado de entidades como a Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria de Mato Grosso (Famato), que congrega todos os Sindicatos Rurais do Estado, e do Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea), o Senar integra o Sistema Famato, sendo respons\u00e1vel pelas a\u00e7\u00f5es de aprendizagem e qualifica\u00e7\u00e3o rural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Sistema Famato\/Senar, Rui Prado, \u00e9 o novo membro titular do Conselho Deliberativo do Servi\u00e7o Nacional de Aprendizagem Rural Nacional em Bras\u00edlia (Senar Central) no tri\u00eanio 2012\/2014.\u00a0 Prado foi indicado pela presidente do Conselho Nacional de Agricultura (CNA), senadora K\u00e1tia Abreu, no in\u00edcio do m\u00eas. Nessa quinta-feira (15.03), \u00e0s 9h, ele ir\u00e1 participar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11046","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 13 de mar\u00e7o de 2012","modified":"Atualizado em 13 de mar\u00e7o de 2012"},"absolute_dates_time":{"created":"Publicado em 13 de mar\u00e7o de 2012 15:21","modified":"Atualizado em 13 de mar\u00e7o de 2012 15:21"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11046"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11046\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}