{"id":11033,"date":"2012-01-12T10:17:24","date_gmt":"2012-01-12T12:17:24","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/01\/12\/credenciamento-de-novos-instrutores-do-senar-mt-termina-dia-15\/"},"modified":"2012-01-12T10:17:24","modified_gmt":"2012-01-12T12:17:24","slug":"credenciamento-de-novos-instrutores-do-senar-mt-termina-dia-15","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/01\/12\/credenciamento-de-novos-instrutores-do-senar-mt-termina-dia-15\/","title":{"rendered":"Credenciamento de novos instrutores do Senar-MT termina dia 15"},"content":{"rendered":"<p>As inscri\u00e7\u00f5es para o credenciamento de novos instrutores para os cursos promovidos pelo Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) encerram no pr\u00f3ximo domingo (15.01). Para participar, os interessados devem acessar o site do Sistema Famato (www.sistemafamato.org.br) e clicar no banner &quot;Seja um instrutor do Senar-MT&quot; para fazer a inscri\u00e7\u00e3o.<\/p>\n<p>Segundo o superintendente do Senar-MT, Tiago Mattosinho, ser\u00e3o ofertadas 150 vagas para diversas \u00e1reas. O candidato precisa ser graduado na \u00e1rea desejada. Mas, se o interessado tiver n\u00edvel t\u00e9cnico e experi\u00eancia, tamb\u00e9m poder\u00e1 participar.<\/p>\n<p>&quot;Estamos em busca de profissionais formados, principalmente no campo das ci\u00eancias agr\u00e1rias que s\u00e3o mais demandadas, como veterin\u00e1rios, zootecnistas, engenheiros agr\u00f4nomos e florestais. No entanto, tamb\u00e9m h\u00e1 vagas para outros segmentos como administra\u00e7\u00e3o de empresas e contabilidade, entre outros setores que se enquadram nos perfis dos 110 cursos que oferecemos nas 180 mil propriedades do estado&quot;, explicou Mattosinho.  <\/p>\n<p>Conforme o superintendente, atualmente a entidade conta com 300 instrutores. Para 2012, a meta \u00e9 qualificar 52.000 trabalhadores, o que representa um crescimento de 20% em compara\u00e7\u00e3o a 2010, quando foram formados 42.000 pessoas. A maior procura por treinamentos \u00e9 para operadores de m\u00e1quinas agr\u00edcolas, manejo e recupera\u00e7\u00e3o de pastagens, confinamento de bovinos, piscicultura, armazenamento e classifica\u00e7\u00e3o de gr\u00e3os, insemina\u00e7\u00e3o artificial de bovinos e para a NR 31.8, que trata da sa\u00fade e seguran\u00e7a do trabalhador. <\/p>\n<p>&quot;Um dos principais entraves que encontramos atualmente no agroneg\u00f3cio \u00e9 m\u00e3o de obra qualificada. Para suprir essa defici\u00eancia, faremos um trabalho cont\u00ednuo de credenciamento de novos instrutores. Por atuarmos em todo o estado, \u00e9 fundamental que cada um de nossos nove escrit\u00f3rios regionais de supervis\u00e3o esteja sempre estruturado com bons profissionais&quot;.<\/p>\n<p>Para informa\u00e7\u00f5es, o edital de credenciamento continuar\u00e1 dispon\u00edvel durante 2012 para profissionais nas \u00e1reas citadas acima. No entanto, a primeira etapa de credenciamento, que encerra dia 15, ter\u00e1 como prioridade os profissionais j\u00e1 cadastrados.<\/p>\n<p>O Senar-MT \u00e9 uma institui\u00e7\u00e3o de ensino n\u00e3o formal, voltada para produtores, trabalhadores rurais e seus familiares. Procura, por meio de eventos educacionais, mant\u00ea-los em sintonia com as exig\u00eancias do mercado do trabalho, dando oportunidade para especializa\u00e7\u00e3o e qualifica\u00e7\u00e3o em diferentes ocupa\u00e7\u00f5es. Assim como os 86 sindicatos rurais de Mato Grosso, representados pela Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria de Mato Grosso (Famato), e o Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea), o Senar-MT tamb\u00e9m faz parte do Sistema Famato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es para o credenciamento de novos instrutores para os cursos promovidos pelo Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) encerram no pr\u00f3ximo domingo (15.01). Para participar, os interessados devem acessar o site do Sistema Famato (www.sistemafamato.org.br) e clicar no banner &quot;Seja um instrutor do Senar-MT&quot; para fazer a inscri\u00e7\u00e3o. Segundo o superintendente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11033","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 12 de janeiro de 2012","modified":"Atualizado em 12 de janeiro de 2012"},"absolute_dates_time":{"created":"Publicado em 12 de janeiro de 2012 10:17","modified":"Atualizado em 12 de janeiro de 2012 10:17"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11033"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11033\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}