{"id":11020,"date":"2011-11-21T11:32:32","date_gmt":"2011-11-21T13:32:32","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2011\/11\/21\/meta-de-atendimento-em-2011-mais-que-dobra\/"},"modified":"2011-11-21T11:32:32","modified_gmt":"2011-11-21T13:32:32","slug":"meta-de-atendimento-em-2011-mais-que-dobra","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2011\/11\/21\/meta-de-atendimento-em-2011-mais-que-dobra\/","title":{"rendered":"Meta de atendimento em 2011 mais que dobra"},"content":{"rendered":"<p>O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) comemora o sucesso do programa  Mutir\u00e3o Rural, que leva \u00e0s popula\u00e7\u00f5es mais distantes do estado servi\u00e7os assistenciais em diversas \u00e1reas. Neste m\u00eas de novembro, o Mutir\u00e3o atingiu a marca de 53 mil atendimentos em 23 eventos, superando assim a expectativa para o ano, que era de 25 mil atendimentos. <\/p>\n<p>De acordo com o superintendente do Senar-MT, Tiago Mattosinho, uma remodela\u00e7\u00e3o no formato do evento foi o que permitiu dobrar o n\u00famero de atendimentos. &quot;Tradicionalmente, nos desloc\u00e1vamos de Cuiab\u00e1 para o local do evento e retorn\u00e1vamos \u00e0 sede do Senar-MT, o que geralmente durava tr\u00eas dias, pois eram dois dias s\u00f3 de percurso. Ap\u00f3s alguns ajustes com a equipe, no objetivo de angariar parcerias mais consistentes, decidimos realizar os mutir\u00f5es rurais em v\u00e1rias localidades de uma s\u00f3 vez por meio de uma &#039;rota&#039; predefinida em v\u00e1rias localidades. Para o ano que vem, j\u00e1 estamos revendo os produtos e servi\u00e7os oferecidos pelo Mutir\u00e3o e vamos inovar ainda mais&quot;.<\/p>\n<p>Durante os eventos, os participantes t\u00eam a oportunidade de receber atendimentos gratuitos nas \u00e1reas da sa\u00fade, educa\u00e7\u00e3o, cultura, esporte, lazer, bem como emiss\u00e3o de documentos (RG, CPF, carteira de trabalho, t\u00edtulo de eleitor e certid\u00e3o de nascimento). O Mutir\u00e3o \u00e9 realizado em parceria com os sindicatos rurais, prefeituras, \u00f3rg\u00e3os estaduais e envolve empresas e as comunidades locais no trabalho volunt\u00e1rio. &quot;Interessante notar que hoje muitas institui\u00e7\u00f5es t\u00eam feito uma administra\u00e7\u00e3o human\u00edstica de fato. E isso \u00e9 louv\u00e1vel&quot;, disse o coordenador do Mutir\u00e3o, Jo\u00e3o Vargas.<\/p>\n<p>Foi o caso de Conquista D\u2019Oeste, destaque no m\u00eas de outubro, quando foram realizados 7,4 mil atendimentos. O evento contou com a parceria de uma empresa local, a Mineradora Apoena. De acordo com a supervisora de responsabilidade social da empresa, Vida Maria Souza, a organiza\u00e7\u00e3o j\u00e1 realizou tr\u00eas eventos nesses moldes, mas nessa edi\u00e7\u00e3o teve a oportunidade de contar com o apoio Senar-MT. <\/p>\n<p>&quot;Aliamos nossos esfor\u00e7os numa mesma a\u00e7\u00e3o, integrando o nosso projeto social com o Mutir\u00e3o Rural. Com isso, ganhamos efici\u00eancia, e a comunidade ganhou mais servi\u00e7os. Sem essa parceria, seria imposs\u00edvel atingirmos esse n\u00famero de pessoas&quot;. Vida Souza informou ainda que no dia do evento foram entregues \u00e0 popula\u00e7\u00e3o 900 t\u00edtulos de eleitor que aguardavam despache.   <\/p>\n<p>Para levar cidadania aos munic\u00edpios mais distantes da capital, a caravana j\u00e1 percorreu mais de 30 mil quil\u00f4metros. Conforme o presidente do Sistema Famato, Rui Prado, esses n\u00fameros dever\u00e3o ultrapassar 35 mil quil\u00f4metros, pois ainda restam 14 munic\u00edpios para sediar o Mutir\u00e3o. &quot;Com isso, acreditamos que o n\u00famero de atendimentos dever\u00e1 chegar \u00e0 casa dos 60 mil neste ano&quot;. <\/p>\n<p>O Senar-MT deu in\u00edcio aos trabalhos de mutir\u00f5es rurais em 1996, quando fez seu primeiro evento na comunidade de Aric\u00e1, no munic\u00edpio de Cuiab\u00e1. De l\u00e1 para c\u00e1, os resultados positivos fizeram com que a institui\u00e7\u00e3o mantivesse os trabalhos anuais. Participam dos eventos entidades como a Empaer (Empresa Mato-grossense de Pesquisa, Assist\u00eancia e Extens\u00e3o Rural), o Indea (Instituto de Defesa Agropecu\u00e1ria do Estado de Mato Grosso), o Sebrae (Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas), o  Instituto Nacional de Coloniza\u00e7\u00e3o e Reforma Agr\u00e1ria (Incra), cooperativas e associa\u00e7\u00f5es rurais.<\/p>\n<p>O Senar-MT (Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso) \u00e9 a entidade que atua na profissionaliza\u00e7\u00e3o rural voltada a homens e mulheres de todo o estado. Juntamente com o Imea (Instituto Mato-grossense de Economia Agropecu\u00e1ria) e os Sindicatos Rurais, comp\u00f5e o Sistema Famato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) comemora o sucesso do programa Mutir\u00e3o Rural, que leva \u00e0s popula\u00e7\u00f5es mais distantes do estado servi\u00e7os assistenciais em diversas \u00e1reas. Neste m\u00eas de novembro, o Mutir\u00e3o atingiu a marca de 53 mil atendimentos em 23 eventos, superando assim a expectativa para o ano, que era [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11020","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 14 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 21 de novembro de 2011","modified":"Atualizado em 21 de novembro de 2011"},"absolute_dates_time":{"created":"Publicado em 21 de novembro de 2011 11:32","modified":"Atualizado em 21 de novembro de 2011 11:32"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=11020"}],"version-history":[{"count":0,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/11020\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=11020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=11020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=11020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}