{"id":10671,"date":"2012-10-26T11:49:09","date_gmt":"2012-10-26T13:49:09","guid":{"rendered":"https:\/\/sistemafamato.org.br\/senarmt\/2014\/02\/26\/senar-mt-abre-edital-para-contratar-novos-colaboradores\/"},"modified":"2021-11-13T12:56:06","modified_gmt":"2021-11-13T15:56:06","slug":"senar-mt-abre-edital-para-contratar-novos-colaboradores","status":"publish","type":"post","link":"https:\/\/sistemafamato.org.br\/senarmt\/2012\/10\/26\/senar-mt-abre-edital-para-contratar-novos-colaboradores\/","title":{"rendered":"Senar-MT abre edital para contratar novos colaboradores"},"content":{"rendered":"<p>\nO Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) &nbsp;abriu processo seletivo para contrata&ccedil;&atilde;o de novos colaboradores. O edital pode ser acessado pelo site do Sistema Famato (<a href=\"http:\/\/www.sistemafamato.org.br\">www.sistemafamato.org.br<\/a>) ou do Grupo Valure (<a href=\"http:\/\/www.grupovalure.com.br\">www.grupovalure.com.br<\/a>), empresa que ir&aacute; conduzir a sele&ccedil;&atilde;o. De acordo com o superintendente do Senar, Tiago Mattosinho, o processo pretende preencher 18 vagas de emprego.&nbsp; Desse total, 17 ser&atilde;o lotados na sede do Senar, em Cuiab&aacute;, e uma vaga est&aacute; destinada a regional de Campo Novo do Parecis (396 km a Noroeste da Capital).<\/p>\n<p>\nPara participar da sele&ccedil;&atilde;o o candidato deve fazer a inscri&ccedil;&atilde;o, gratuita, pelo site do Grupo Valore, de hoje (26.10) at&eacute; &agrave;s 18h00 do dia 05 de novembro de 2012. O processo de sele&ccedil;&atilde;o ser&aacute; realizado em tr&ecirc;s etapas. A primeira etapa &eacute; de analise curricular, a segunda constitui-se de uma din&acirc;mica de grupo seguida por uma prova de reda&ccedil;&atilde;o. A terceira e ultima etapa ser&aacute; a entrevista e an&aacute;lise psicol&oacute;gica.&nbsp; As datas das duas &uacute;ltimas etapas ser&atilde;o informadas oportunamente pela empresa respons&aacute;vel pelo processo.<\/p>\n<p>\nS&atilde;o cinco vagas para analista de Educa&ccedil;&atilde;o Profissional, que ter&atilde;o a fun&ccedil;&atilde;o de acompanhar, avaliar e controlar a elabora&ccedil;&atilde;o do Plano Anual de Trabalho (PAT) do Senar-MT e outras atividades. A exig&ecirc;ncia &eacute; ter curso superior em Medicina Veterin&aacute;ria, Agronomia e Zootecnia. O sal&aacute;rio ser&aacute; de R$3.500,00 para oito horas, al&eacute;m de benef&iacute;cios como vale alimenta&ccedil;&atilde;o<strong>, <\/strong>seguro de vida em grupo e plano de sa&uacute;de ap&oacute;s periodo de experi&ecirc;ncia. H&aacute; vaga para analista jur&iacute;dico, exige-se dedica&ccedil;&atilde;o exclusiva e que o candidato seja inscrito na Ordem dos Advogados do Brasil (OAB). A institui&ccedil;&atilde;o de ensino rural tamb&eacute;m est&aacute; contratando analista em Comunica&ccedil;&atilde;o Marketing e Eventos, com forma&ccedil;&atilde;o superior na &aacute;rea de Comunica&ccedil;&atilde;o Social.<\/p>\n<p>\nO processo seletivo tamb&eacute;m busca designer gr&aacute;fico, assistente administrativo (de Aquisi&ccedil;&atilde;o e Suprimentos, e cont&aacute;bil), assistente de Aprendizagem Rural, auxiliar administrativo (de Educa&ccedil;&atilde;o Profissional), tesoureiro e zelador. As exig&ecirc;ncias e a remunera&ccedil;&atilde;o para cada vaga constam no edital. Todos os contratados ser&atilde;o pelo regime da Consolida&ccedil;&atilde;o das Leis Trabalhistas (CLT).<\/p>\n<p>\nO superintendente do Senar-MT explica que as novas contrata&ccedil;&otilde;es fazem parte do Plano de Expans&atilde;o da institui&ccedil;&atilde;o que acompanha a evolu&ccedil;&atilde;o do setor agropecu&aacute;rio de Mato Grosso.&nbsp; &quot;Nos &uacute;ltimos 10 anos tivemos um enorme crescimento no setor rural do Estado e o Senar cresceu junto, tanto em rela&ccedil;&atilde;o a sua estrutura quanto em rela&ccedil;&atilde;o &agrave; arrecada&ccedil;&atilde;o&quot;, explica. &quot;Esse crescimento exigiu um plano de expans&atilde;o, para que possamos atender as novas demandas por treinamentos e cursos de capacita&ccedil;&atilde;o&quot;, completa. O processo seletivo est&aacute; sendo divulgado tamb&eacute;m em jornais, r&aacute;dios, e nas principais faculdades de Cuiab&aacute;.<\/p>\n<p>\nO Senar est&aacute; no Twitter e no Facebook. Siga <a href=\"mailto:@senar_mt\"><strong>@senar_mt<\/strong><\/a> e curta a Fan Page (<a href=\"http:\/\/www.facebook.com\/SenarMt\" target=\"_blank\" title=\"Link de acesso\" rel=\"noopener\"><strong>http:\/\/www.facebook.com\/SenarMt<\/strong><\/a>) da institui&ccedil;&atilde;o de ensino rural que est&aacute; presente em todos os munic&iacute;pios de Mato Grosso, atuando em parceria com os 86 sindicatos rurais. Faz parte do Sistema Famato, assim como a Federa&ccedil;&atilde;o da Agricultura e Pecu&aacute;ria do Estado de Mato Grosso (Famato) e o Instituto Mato-grossense de Economia Agropecu&aacute;ria (IMEA-MT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi&ccedil;o Nacional de Aprendizagem Rural de Mato Grosso (Senar-MT) &nbsp;abriu processo seletivo para contrata&ccedil;&atilde;o de novos colaboradores. O edital pode ser acessado pelo site do Sistema Famato (www.sistemafamato.org.br) ou do Grupo Valure (www.grupovalure.com.br), empresa que ir&aacute; conduzir a sele&ccedil;&atilde;o. De acordo com o superintendente do Senar, Tiago Mattosinho, o processo pretende preencher 18 vagas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-10671","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"author_meta":{"display_name":"siteadmin","author_link":"https:\/\/sistemafamato.org.br\/senarmt\/author\/siteadmin\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sistemafamato.org.br\/senarmt\/category\/geral\/\" class=\"advgb-post-tax-term\">Geral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Geral<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 14 anos atr\u00e1s","modified":"Atualizado 4 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 26 de outubro de 2012","modified":"Atualizado em 13 de novembro de 2021"},"absolute_dates_time":{"created":"Publicado em 26 de outubro de 2012 11:49","modified":"Atualizado em 13 de novembro de 2021 12:56"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/10671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/comments?post=10671"}],"version-history":[{"count":1,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/10671\/revisions"}],"predecessor-version":[{"id":11189,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/posts\/10671\/revisions\/11189"}],"wp:attachment":[{"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/media?parent=10671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/categories?post=10671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafamato.org.br\/senarmt\/wp-json\/wp\/v2\/tags?post=10671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}